{"id":1958,"date":"2026-01-20T15:24:03","date_gmt":"2026-01-20T14:24:03","guid":{"rendered":"http:\/\/mivv2026.local\/mivv-racing\/mivv-in-der-motogp\/"},"modified":"2026-04-23T10:58:56","modified_gmt":"2026-04-23T08:58:56","slug":"mivv-in-der-motogp","status":"publish","type":"page","link":"https:\/\/dev.mivv.com\/de\/racing\/mivv-in-der-motogp\/","title":{"rendered":"Mivv in der MotoGP"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column sidebar-baz is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<p style=\"font-style:normal;font-weight:700\"><strong>Index<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>2010<\/strong>\n<ul class=\"wp-block-list\">\n<li><a href=\"#repsol-honda-team-stagione-2010\" rel=\"nofollow\">REPSOL HONDATEAM<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>2009<\/strong>\n<ul class=\"wp-block-list\">\n<li><a href=\"#repsol-honda-team-stagione-2009\" rel=\"nofollow\">REPSOL HONDA TEAM<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>2008<\/strong>\n<ul class=\"wp-block-list\">\n<li><a href=\"#repsol-honda-team-stagione-2008\" rel=\"nofollow\">REPSOL HONDA TEAM<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>2007<\/strong>\n<ul class=\"wp-block-list\">\n<li><a href=\"#repsol-honda-team-stagione-2007\" rel=\"nofollow\">REPSOL HONDA TEAM<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>2006<\/strong>\n<ul class=\"wp-block-list\">\n<li><a href=\"#repsol-honda-team-stagione-2006\" rel=\"nofollow\">REPSOL HONDA TEAM<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column content-sidebar-baz is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<div id=\"repsol-honda-team-stagione-2010\" class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" style=\"font-size:60px;font-style:normal;font-weight:700\">SAISON 2010<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">REPSOL HONDA TEAM<\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Das Team bleibt f\u00fcr 2010 unver\u00e4ndert. In dieser Saison feierte die Moto2-Klasse Premiere und ersetzte die 250-ccm-Klasse. Die Weltmeisterschaft wurde vom Tod des Fahrers Shoya Tomizawa \u00fcberschattet, der auf dem Misano Circuit von De Angelis und Redding erfasst wurde.<br\/>Zur\u00fcck im Repsol Honda Team fuhren beide Werksfahrer unter die ersten F\u00fcnf: Pedrosa belegte mit vier Siegen und f\u00fcnf zweiten Pl\u00e4tzen den zweiten Platz. Dovizioso wurde F\u00fcnfter: Er konnte zwar keinen Sieg erringen, landete aber fast immer unter den ersten Drei. Wie schon im Vorjahr verdiente sich das Team den zweiten Platz in der Hersteller- und Teamwertung redlich. Auch Mivv zeigte sich mit den in dieser Saison erzielten Ergebnissen zufrieden. Der Speed \u200b\u200bEdge Auspuff, der sich durch ein intelligentes Design auszeichnet und optimal auf das Fahrwerk des Motorrads abgestimmt ist, wurde f\u00fcr den Stra\u00dfen-Zubeh\u00f6rmarkt entwickelt.    <\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-cb-carousel-v2 cb-carousel-block cb-single-slide\" data-cb-slides-per-view=\"1\" data-cb-slides-per-group=\"1\" data-cb-space-between=\"15\" data-cb-speed=\"300\" data-cb-pagination=\"true\" data-cb-loop=\"true\" data-cb-autoplay=\"true\" data-cb-autoplay-speed=\"3000\" data-cb-breakpoints=\"{&quot;768&quot;:{&quot;slidesPerView&quot;:1,&quot;slidesPerGroup&quot;:1}}\"><div class=\"swiper\"><div class=\"cb-wrapper swiper-wrapper\">\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"542\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Pedrosa-2010-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-432\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2010-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2010-Mivv-850x0-1-600x383.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2010-Mivv-850x0-1-300x191.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2010-Mivv-850x0-1-768x490.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"565\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Pedrosa2-2010-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-431\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa2-2010-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa2-2010-Mivv-850x0-1-600x399.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa2-2010-Mivv-850x0-1-300x199.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa2-2010-Mivv-850x0-1-768x510.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Dovizioso-2010-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-430\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso-2010-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso-2010-Mivv-850x0-1-600x400.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso-2010-Mivv-850x0-1-300x200.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso-2010-Mivv-850x0-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"565\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Dovizioso2-2010-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-429\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso2-2010-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso2-2010-Mivv-850x0-1-600x399.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso2-2010-Mivv-850x0-1-300x199.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso2-2010-Mivv-850x0-1-768x510.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n<\/div><\/div><div class=\"cb-pagination swiper-pagination\"><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"repsol-honda-team-stagione-2009\" class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" style=\"font-size:60px;font-style:normal;font-weight:700\">SAISON 2009<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">REPSOL HONDA TEAM<\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Diese Meisterschaft markierte den Generationswechsel zwischen dem Amerikaner Hayden und dem Italiener Andrea Dovizioso, w\u00e4hrend Pedrosa seinen Platz im Team behielt. Die MotoGP-Saison sollte urspr\u00fcnglich 18 Rennen umfassen, darunter den Gro\u00dfen Preis von Ungarn, der um zwei Jahre verschoben und schlie\u00dflich durch den Gro\u00dfen Preis von Aragon ersetzt wurde.<br\/>Die Endergebnisse belohnten das Team HRC\/Honda Repsol mit einem starken zweiten Platz in der Konstrukteurs- und Teamwertung. Pedrosa musste sich mit dem dritten Platz in der Gesamtwertung begn\u00fcgen, nachdem er zwei Siege und neun weitere Podiumspl\u00e4tze errungen hatte. Dovi beendete die Saison mit einem Sieg und mehreren guten Platzierungen und sicherte sich den sechsten Platz in der Gesamtwertung. Die Zusammenarbeit zwischen Mivv und dem Honda Repsol Team ist so intensiv wie in den vergangenen Saisons.  <\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-cb-carousel-v2 cb-carousel-block cb-single-slide\" data-cb-slides-per-view=\"1\" data-cb-slides-per-group=\"1\" data-cb-space-between=\"15\" data-cb-speed=\"300\" data-cb-pagination=\"true\" data-cb-loop=\"true\" data-cb-autoplay=\"true\" data-cb-autoplay-speed=\"3000\" data-cb-breakpoints=\"{&quot;768&quot;:{&quot;slidesPerView&quot;:1,&quot;slidesPerGroup&quot;:1}}\"><div class=\"swiper\"><div class=\"cb-wrapper swiper-wrapper\">\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Dovizioso-2009-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-443\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso-2009-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso-2009-Mivv-850x0-1-600x400.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso-2009-Mivv-850x0-1-300x200.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso-2009-Mivv-850x0-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"606\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Dovizioso-Pedrosa-2009-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-444\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso-Pedrosa-2009-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso-Pedrosa-2009-Mivv-850x0-1-600x428.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso-Pedrosa-2009-Mivv-850x0-1-300x214.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Dovizioso-Pedrosa-2009-Mivv-850x0-1-768x548.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n<\/div><\/div><div class=\"cb-pagination swiper-pagination\"><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"repsol-honda-team-stagione-2008\" class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" style=\"font-size:60px;font-style:normal;font-weight:700\">SAISON 2008<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">REPSOL HONDA TEAM<\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Pedrosa und Hayden fahren zum dritten Mal in Folge die Werks-Hondas. Es gab einige personelle Ver\u00e4nderungen: Mike Leitner und Pete Benson sind nun die beiden Chefmechaniker, Kazuhiko Yamano \u00fcbernimmt die Teamleitung. Pedrosa wechselte im Laufe der Saison die Reifen; der Wechsel zu Bridgestone f\u00fchrte dazu, dass zwischen Dani und Nicky in der Box eine Trennwand errichtet wurde, um die Reifendaten vor neugierigen Blicken zu sch\u00fctzen. Eine \u00e4hnliche L\u00f6sung gab es bereits zu Saisonbeginn zwischen Rossi und seinem Teamkollegen\/Rivalen Lorenzo.<br\/>Das Honda Repsol Team belegte sowohl in der Fahrerwertung (mit zwei Siegen und neun weiteren Podiumspl\u00e4tzen von Dani Pedrosa) als auch in der Konstrukteurswertung den dritten Platz. In der Teamwertung schnitt das Team mit dem zweiten Platz besser ab. Nicky Hayden konnte nicht \u00fcberzeugen und stand nur zweimal auf dem Podium (Platz zwei und drei). Mivv unterst\u00fctzt das Team auch in dieser Saison und steht jederzeit f\u00fcr dessen Bed\u00fcrfnisse zur Verf\u00fcgung.     <\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-cb-carousel-v2 cb-carousel-block cb-single-slide\" data-cb-slides-per-view=\"1\" data-cb-slides-per-group=\"1\" data-cb-space-between=\"15\" data-cb-speed=\"300\" data-cb-pagination=\"true\" data-cb-loop=\"true\" data-cb-autoplay=\"true\" data-cb-autoplay-speed=\"3000\" data-cb-breakpoints=\"{&quot;768&quot;:{&quot;slidesPerView&quot;:1,&quot;slidesPerGroup&quot;:1}}\"><div class=\"swiper\"><div class=\"cb-wrapper swiper-wrapper\">\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Hayden-2008-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-446\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-2008-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-2008-Mivv-850x0-1-600x400.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-2008-Mivv-850x0-1-300x200.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-2008-Mivv-850x0-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Pedrosa2-2008-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-447\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa2-2008-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa2-2008-Mivv-850x0-1-600x400.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa2-2008-Mivv-850x0-1-300x200.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa2-2008-Mivv-850x0-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Pedrosa-2008-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-448\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2008-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2008-Mivv-850x0-1-600x400.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2008-Mivv-850x0-1-300x200.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2008-Mivv-850x0-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n<\/div><\/div><div class=\"cb-pagination swiper-pagination\"><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"repsol-honda-team-stagione-2007\" class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" style=\"font-size:60px;font-style:normal;font-weight:700\">SAISON 2007<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">REPSOL HONDA TEAM<\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Die Fahrerbesetzung blieb f\u00fcr die Saison 2007 unver\u00e4ndert. In diesem Jahr setzte das Team die neue 800-cm\u00b3-Honda RC212V ein, um den neuen FIM-Regularien zu entsprechen, die den Hubraum von 990 cm\u00b3 auf 800 cm\u00b3 reduzierten. Anfangs blieb der erwartete Erfolg aus, doch dank Weiterentwicklung verbesserte sich die Leistung im Laufe der Rennen. <br\/>Pedrosa errang zwei Siege und sechs weitere Podiumspl\u00e4tze und beendete die Saison als Zweiter hinter Casey Stoner. Hayden wurde Achter in der Fahrerwertung mit vier dritten Pl\u00e4tzen. Honda und das Repsol-Team belegten den zweiten Platz in der Konstrukteurs- und Teamwertung.<br\/>Mivv arbeitete eng mit dem Honda Repsol-Team zusammen und kn\u00fcpfte an die Erfolge des Vorjahres an. Der Suono-Auspuff, Ergebnis einer intensiven und innovativen Designstudie, wurde f\u00fcr den Stra\u00dfen-Nachr\u00fcstmarkt entwickelt.   <br\/><\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-cb-carousel-v2 cb-carousel-block cb-single-slide\" data-cb-slides-per-view=\"1\" data-cb-slides-per-group=\"1\" data-cb-space-between=\"15\" data-cb-speed=\"300\" data-cb-pagination=\"true\" data-cb-loop=\"true\" data-cb-autoplay=\"true\" data-cb-autoplay-speed=\"3000\" data-cb-breakpoints=\"{&quot;768&quot;:{&quot;slidesPerView&quot;:1,&quot;slidesPerGroup&quot;:1}}\"><div class=\"swiper\"><div class=\"cb-wrapper swiper-wrapper\">\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Hayden-2007-Mivv-850x0-2.jpg\" alt=\"\" class=\"wp-image-449\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-2007-Mivv-850x0-2.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-2007-Mivv-850x0-2-600x400.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-2007-Mivv-850x0-2-300x200.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-2007-Mivv-850x0-2-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"846\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Hayden-Pedrosa-2007-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-450\" style=\"aspect-ratio:4\/3;object-fit:cover\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-Pedrosa-2007-Mivv-850x0-1.jpg 800w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-Pedrosa-2007-Mivv-850x0-1-600x635.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-Pedrosa-2007-Mivv-850x0-1-284x300.jpg 284w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-Pedrosa-2007-Mivv-850x0-1-768x812.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Honda-RC212V-2007-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-451\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Honda-RC212V-2007-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Honda-RC212V-2007-Mivv-850x0-1-600x400.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Honda-RC212V-2007-Mivv-850x0-1-300x200.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Honda-RC212V-2007-Mivv-850x0-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Pedrosa-2007-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-452\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2007-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2007-Mivv-850x0-1-600x400.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2007-Mivv-850x0-1-300x200.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2007-Mivv-850x0-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n<\/div><\/div><div class=\"cb-pagination swiper-pagination\"><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div id=\"repsol-honda-team-stagione-2006\" class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\" style=\"font-size:60px;font-style:normal;font-weight:700\">SAISON 2006<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">REPSOL HONDA TEAM<\/h3>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Es geht sofort richtig los: Die Saison 2006 bringt <strong>den Titelgewinn von Nicky Hayden<\/strong>. Sein Teamkollege ist <strong>Dani Pedrosa<\/strong>, bereits Weltmeister in der 250er-Klasse.<br\/>Nicky f\u00fchrt die Meisterschaftswertung \u00fcber weite Strecken der Saison an. Der R\u00fcckschlag kommt beim Portugal-GP nach einem Unfall, der nicht nur ihn, sondern auch seinen Teamkollegen betrifft: Rossi \u00fcbernimmt wieder die F\u00fchrung in der Meisterschaft. Alles entscheidet sich im letzten Rennen, in dem Rossi in der 5. Runde spektakul\u00e4r st\u00fcrzt: Hayden wird durch seinen dritten Platz Weltmeister. Pedrosa beendet die Saison auf Platz 5, mit 2 Rennsiegen und weiteren 5 Podestpl\u00e4tzen. Auf der EICMA 2006 wird der amerikanische Fahrer am Mivv-Stand gefeiert; eigens daf\u00fcr werden ein Podium und ein \u00f6ffentliches Interview vorbereitet.<br\/>Im ersten Jahr der Zusammenarbeit unterst\u00fctzt Mivv die Bed\u00fcrfnisse des Teams bestm\u00f6glich. Der WM-Titel belohnt die Anstrengungen der gesamten Rennsaison. F\u00fcr den Stra\u00dfen-Aftermarket wird anschlie\u00dfend der <strong>GP-Auspuff<\/strong> entwickelt \u2013 basierend auf den im Motomondiale gewonnenen Erfahrungen.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-cb-carousel-v2 cb-carousel-block cb-single-slide\" data-cb-slides-per-view=\"1\" data-cb-slides-per-group=\"1\" data-cb-space-between=\"15\" data-cb-speed=\"300\" data-cb-pagination=\"true\" data-cb-loop=\"true\" data-cb-autoplay=\"true\" data-cb-autoplay-speed=\"3000\" data-cb-breakpoints=\"{&quot;768&quot;:{&quot;slidesPerView&quot;:1,&quot;slidesPerGroup&quot;:1}}\"><div class=\"swiper\"><div class=\"cb-wrapper swiper-wrapper\">\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Hayden-2006-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-453\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-2006-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-2006-Mivv-850x0-1-600x400.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-2006-Mivv-850x0-1-300x200.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-2006-Mivv-850x0-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Hayden-e-Pedrosa-2006-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-454\" style=\"aspect-ratio:4\/3;object-fit:cover\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-e-Pedrosa-2006-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-e-Pedrosa-2006-Mivv-850x0-1-600x400.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-e-Pedrosa-2006-Mivv-850x0-1-300x200.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Hayden-e-Pedrosa-2006-Mivv-850x0-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cb-slide-v2 cb-slide swiper-slide\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"http:\/\/mivv2026.local\/wp-content\/uploads\/2026\/01\/Pedrosa-2006-Mivv-850x0-1.jpg\" alt=\"\" class=\"wp-image-456\" srcset=\"https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2006-Mivv-850x0-1.jpg 850w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2006-Mivv-850x0-1-600x400.jpg 600w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2006-Mivv-850x0-1-300x200.jpg 300w, https:\/\/dev.mivv.com\/wp-content\/uploads\/2026\/01\/Pedrosa-2006-Mivv-850x0-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n<\/div><\/div>\n<\/div><\/div><div class=\"cb-pagination swiper-pagination\"><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-black-color has-text-color has-link-color has-text-align-center wp-element-button\" href=\"https:\/\/dev.mivv.com\/de\/racing\/\" style=\"border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px;font-style:normal;font-weight:600;text-transform:uppercase\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" width=\"15\" height=\"15\" class=\"wp-image-3245\" style=\"width: 15px;\" src=\"\/wp-content\/uploads\/2026\/03\/icons8-indietro-48.png\" alt=\"\"\/> Zur\u00fcck zu Racing<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Index SAISON 2010 REPSOL HONDA TEAM Das Team bleibt f\u00fcr 2010 unver\u00e4ndert. In dieser Saison feierte die Moto2-Klasse Premiere und ersetzte die 250-ccm-Klasse. Die Weltmeisterschaft wurde vom Tod des Fahrers Shoya Tomizawa \u00fcberschattet, der auf dem Misano Circuit von De Angelis und Redding erfasst wurde.Zur\u00fcck im Repsol Honda Team fuhren beide Werksfahrer unter die ersten [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":1211,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1958","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/pages\/1958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/comments?post=1958"}],"version-history":[{"count":8,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/pages\/1958\/revisions"}],"predecessor-version":[{"id":105625,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/pages\/1958\/revisions\/105625"}],"up":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/pages\/1211"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=1958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}