{"id":102374,"date":"2026-04-21T14:57:51","date_gmt":"2026-04-21T12:57:51","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-038-lxbp-bmw-f-900-r-2025-2026\/"},"modified":"2026-04-21T14:57:51","modified_gmt":"2026-04-21T12:57:51","slug":"b-038-lxbp-bmw-f-900-r-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/b-038-lxbp-bmw-f-900-r-2025-2026\/","title":{"rendered":"B.038.LXBP \u2013 BMW F 900 R 2025 > 2026"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Das GP PRO zeigt eine <strong>TIG-halb handgefertigte Schwei\u00dfung<\/strong>, ein Kompaktes und <strong>wesentliches Design und einen aggressiven Sound<\/strong> auf. Das von der <strong>Wettbewerbswelt<\/strong> inspirierte Ausgangsauspuffrohr ist mit einer <strong>abnehmbaren Schutzgitter<\/strong> ausgestattet, die den dB-killer verbirgt. Auf dem Endschalld\u00e4mpfer erscheint das durch die Laser-Technologie hergestellte typische Mivv Logo.<\/p>\n<p>Das zeichnet sich durch einen Zentralk\u00f6rper aus schwarzem Edelstahl mit geb\u00fcrstetem <strong>\u201eBlack Moon\u201c<\/strong>-Effekt aus. Der Effekt wurde durch ein spezielles Lackierverfahren erzielt. Diese Bearbeitung verleiht dem Produkt einen <strong>aggressiveren Look.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nur kompatibel mit den Original-Satteltaschen<\/p>\n","protected":false},"featured_media":7789,"template":"","meta":{"_acf_changed":false},"product_brand":[22251,22104,22237],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-102374","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-9375","7":"product_brand-bmw","8":"product_brand-f-900-r","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/102374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/7789"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=102374"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=102374"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=102374"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=102374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}