{"id":102437,"date":"2026-04-21T14:58:27","date_gmt":"2026-04-21T12:58:27","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-037-ldrb-bmw-f-900-xr-2025-2026\/"},"modified":"2026-04-21T14:58:27","modified_gmt":"2026-04-21T12:58:27","slug":"b-037-ldrb-bmw-f-900-xr-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/b-037-ldrb-bmw-f-900-xr-2025-2026\/","title":{"rendered":"B.037.LDRB \u2013 BMW F 900 XR 2025 > 2026"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Der DELTA RACE Auspuff zeichnet sich durch eine <strong>exklusive Form<\/strong> aus, die mittels einer allm\u00e4hlichen Umwandlung von einer konischen zu einer <strong>sechseckigen Form wird<\/strong>. Es gibt viele Details, die dessen Stil einzigartig machen; die Kappe aus 3K twill Carbon, die <strong>doppelt genietete<\/strong> umfassende Schelle, die fest gefertigte Eingangsbuchse, um die beste Kupplungsgenauigkeit anzubieten. Auf dem Endschalld\u00e4mpfer erscheint das durch die Laser-Technologie hergestellte typische Mivv Logo.<\/p>\n<p>Das zeichnet sich durch einen Zentralk\u00f6rper aus schwarzem Edelstahl mit einem <strong>\u201cBlack Moon\u201c<\/strong>-Effekt aus. Das wird dank eines Sonderlackierungsprozesses mit Keramik erreicht, der dem Produkt einen <strong>aggressiveren Look verleiht.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EURO 5 HOMOLOGIERT. Homologation nicht g\u00fcltig f\u00fcr Motorr\u00e4der der Version 35 kW. KOMPATIBEL MIT ORIGINAL MITTELST\u00c4NDER<\/p>\n","protected":false},"featured_media":7803,"template":"","meta":{"_acf_changed":false},"product_brand":[22272,22104,22259],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-102437","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-9377","7":"product_brand-bmw","8":"product_brand-f-900-xr","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/102437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/7803"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=102437"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=102437"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=102437"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=102437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}