{"id":102472,"date":"2026-04-21T14:58:49","date_gmt":"2026-04-21T12:58:49","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-036-ldrc-bmw-s-1000-rr-2025-2026\/"},"modified":"2026-04-21T14:58:49","modified_gmt":"2026-04-21T12:58:49","slug":"b-036-ldrc-bmw-s-1000-rr-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/b-036-ldrc-bmw-s-1000-rr-2025-2026\/","title":{"rendered":"B.036.LDRC \u2013 BMW S 1000 RR 2025 > 2026"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Der DELTA RACE Auspuff zeichnet sich durch eine <strong>exklusive Form<\/strong> aus, die mittels einer allm\u00e4hlichen Umwandlung von einer konischen zu einer <strong>sechseckigen Form wird<\/strong>. Es gibt viele Details, die dessen Stil einzigartig machen; die Kappe aus 3K twill Carbon, die <strong>doppelt genietete<\/strong> umfassende Schelle, die fest gefertigte Eingangsbuchse, um die beste Kupplungsgenauigkeit anzubieten. Auf dem Endschalld\u00e4mpfer erscheint das durch die Laser-Technologie hergestellte typische Mivv Logo.<\/p>\n<p>Das zeichnet sich durch einen Hauptk\u00f6rper aus\u00a0Carbon\u00a0mit\u00a0<strong>einer gl\u00e4nzenden Verarbeitung<\/strong>\u00a0aus; das\u00a0<strong>ideale Produkt f\u00fcr diejenigen, die das Beste an Look und Technologie verlangen.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der zur \u00c4sthetik, Sound und Leistungs-Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die sich auch durch den Look seines eigenen Motorrads auszeichnen wollen, zu befriedigen. Der DELTA RACE Auspuff zeichnet sich durch eine exklusive Form aus, die mittels einer allm\u00e4hlichen Umwandlung von einer konischen zu einer [&hellip;]<\/p>\n","protected":false},"featured_media":64968,"template":"","meta":{"_acf_changed":false},"product_brand":[22545,22104,22524],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-102472","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-448","7":"product_brand-bmw","8":"product_brand-s-1000-rr","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/102472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/64968"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=102472"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=102472"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=102472"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=102472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}