{"id":102500,"date":"2026-04-21T14:59:11","date_gmt":"2026-04-21T12:59:11","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-042-lr1t-bmw-r-1300-gs-2025-2026\/"},"modified":"2026-04-21T14:59:11","modified_gmt":"2026-04-21T12:59:11","slug":"b-042-lr1t-bmw-r-1300-gs-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/b-042-lr1t-bmw-r-1300-gs-2025-2026\/","title":{"rendered":"B.042.LR1T &#8211; BMW R 1300 GS 2025 > 2026"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Die Auspuffe der <strong>SR-1<\/strong> Linie sind haupts\u00e4chlich den Superbike und Hypernaked Motorr\u00e4dern gewidmet.\u00a0Die <strong>SR-1<\/strong> Anlage, erbt die ganze Erfahrung, die in den verschiedenen <strong>MotoGp &#8211; Moto2 &#8211; Moto3<\/strong> Weltmeisterschaften gesammelt wurde. Der Auspuff, der mit gro\u00dfer Sorgfalt auf die Details bearbeitet wurde, garantiert eine <strong>Look<\/strong>-sowie eine <strong>Leistungsverbesserung<\/strong> des Motorrads.<\/p>\n<p>Diese Version besteht aus einem <strong>sechseckigen K\u00f6rper aus Titan<\/strong> und einer <strong>Kappe aus Carbon<\/strong> mit T- will Bearbeitung; diese ist gegen heftige Temperaturver\u00e4nderungen best\u00e4ndig, was typisch f\u00fcr <strong>die Racing Welt<\/strong> ist. Im Unterschied zum Serienauspuff, garantiert die SR-1 Anlage aus <strong>Titan<\/strong> eine erhebliche <strong>Gewichtsreduktion<\/strong>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kompatibel mit den originalen Seitentaschen\/Seitenkoffern<\/p>\n","protected":false},"featured_media":65452,"template":"","meta":{"_acf_changed":false},"product_brand":[22475,22104,22461],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-102500","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-11239","7":"product_brand-bmw","8":"product_brand-r-1300-gs","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/102500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/65452"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=102500"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=102500"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=102500"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=102500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}