{"id":102591,"date":"2026-04-21T15:00:03","date_gmt":"2026-04-21T13:00:03","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-048-lc5b-ducati-monster-937-monster-937-2025-2025\/"},"modified":"2026-04-21T15:00:03","modified_gmt":"2026-04-21T13:00:03","slug":"d-048-lc5b-ducati-monster-937-monster-937-2025-2025","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/d-048-lc5b-ducati-monster-937-monster-937-2025-2025\/","title":{"rendered":"D.048.LC5B \u2013 DUCATI MONSTER 937 \/ MONSTER 937 + 2025 > 2025"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Die Mivv <strong>X-M5<\/strong>-Linie,ist das Ergebnis der in der <strong>MotoGP, Moto2<\/strong> und <strong>Moto3<\/strong> Weltmeisterschaften gesammelten Erfahrungen und ist die perfekte Synthese aus <strong>Leistung<\/strong> und <strong>Racing<\/strong>. Mit einem <strong>Design<\/strong>, das den Auspuffanlagen der Motorradweltmeisterschaft sehr \u00e4hnlich ist, hat der <strong>X-M5<\/strong> Endschalld\u00e4mpfer eine <strong>konische<\/strong> Form, mit <strong>kompakten<\/strong> Abmessungen, sowie den unverwechselbaren MIVV-<strong>Sound<\/strong>.<\/p>\n<p>Der D\u00e4mpfer hat eine Kappe aus <strong>carbon<\/strong> twill 3K und ist mit einem <strong>herausnehmbaren Schutzgitter<\/strong> ausgestattet, das den Db Killer verbirgt.<\/p>\n<p>Die <strong>Black<\/strong>-Version zeichnet sich durch einen Schalld\u00e4mpfer aus schwarzem 304 Edelstahl mit einem <strong>\u201cBlack Moon\u201d<\/strong> \u2013 Effekt aus. Der Effekt wird dank eines Sonderlackierungsprozesses mit Keramik erreicht.<\/p>\n<p><strong>X-M5 reiner italienischer Stil<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der zur \u00c4sthetik, Sound und Leistungs-Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die sich auch durch den Look seines eigenen Motorrads auszeichnen wollen, zu befriedigen. Die Mivv X-M5-Linie,ist das Ergebnis der in der MotoGP, Moto2 und Moto3 Weltmeisterschaften gesammelten Erfahrungen und ist die perfekte Synthese aus [&hellip;]<\/p>\n","protected":false},"featured_media":64959,"template":"","meta":{"_acf_changed":false},"product_brand":[22769,23189],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-102591","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-ducati","7":"product_brand-monster-937","8":"product_cat-slip-on","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/102591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/64959"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=102591"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=102591"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=102591"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=102591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}