{"id":104110,"date":"2026-04-21T15:13:29","date_gmt":"2026-04-21T13:13:29","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/acc-101-0-honda-cb-650-r-2024-2026\/"},"modified":"2026-04-21T15:13:29","modified_gmt":"2026-04-21T13:13:29","slug":"acc-101-0-honda-cb-650-r-2024-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/acc-101-0-honda-cb-650-r-2024-2026\/","title":{"rendered":"ACC.101.0 &#8211; HONDA CB 650 R 2024 > 2026"},"content":{"rendered":"<p><p>MIVV SWITCH OFF KEY ist ein elektronisches Plug-and-Play-Selbstdiagnoseger&auml;t (OBD) f&uuml;r Euro5+-Motorr&auml;der mit folgenden Funktionen:<\/p>\n<ul>\n<li>Schaltet die Motorfehleranzeige (Check Engine) aus, wenn diese aufgrund des Austauschs des Originalkatalysators durch ein Aftermarket-Modell aufleuchtet, was zu Abweichungen der Sauerstoffparameter gegen&uuml;ber den vom Originalsteuerger&auml;t voreingestellten Werten f&uuml;hren kann.<\/li>\n<li>Durch das Ausschalten der Check-Engine-Leuchte bleibt gleichzeitig die korrekte Funktion der On-Board-Diagnose erhalten.<\/li>\n<li>Es greift in keiner Weise in die urspr&uuml;ngliche Programmierung des Motorsteuerger&auml;ts oder andere elektronische Parameter des Fahrzeugs ein.<\/li>\n<\/ul>\n<p>Nicht zugelassenes Produkt.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MIVV SWITCH OFF KEY ist ein elektronisches Plug-and-Play-Selbstdiagnoseger&auml;t (OBD) f&uuml;r Euro5+-Motorr&auml;der mit folgenden Funktionen: Schaltet die Motorfehleranzeige (Check Engine) aus, wenn diese aufgrund des Austauschs des Originalkatalysators durch ein Aftermarket-Modell aufleuchtet, was zu Abweichungen der Sauerstoffparameter gegen&uuml;ber den vom Originalsteuerger&auml;t voreingestellten Werten f&uuml;hren kann. Durch das Ausschalten der Check-Engine-Leuchte bleibt gleichzeitig die korrekte Funktion der [&hellip;]<\/p>\n","protected":false},"featured_media":5898,"template":"","meta":{"_acf_changed":false},"product_brand":[24043,24029,23847],"product_cat":[856],"product_tag":[],"class_list":{"0":"post-104110","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2024-2026-9188","7":"product_brand-cb-650-r","8":"product_brand-honda","9":"product_cat-abschaltschlussel","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/104110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/5898"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=104110"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=104110"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=104110"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=104110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}