{"id":104572,"date":"2026-04-21T15:17:57","date_gmt":"2026-04-21T13:17:57","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/a-022-ldrx-aprilia-tuono-125-2025-2026\/"},"modified":"2026-04-21T15:17:57","modified_gmt":"2026-04-21T13:17:57","slug":"a-022-ldrx-aprilia-tuono-125-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/a-022-ldrx-aprilia-tuono-125-2025-2026\/","title":{"rendered":"A.022.LDRX &#8211; APRILIA TUONO 125 2025 > 2026"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Der DELTA RACE Auspuff zeichnet sich durch eine <strong>exklusive Form<\/strong> aus, die mittels einer allm\u00e4hlichen Umwandlung von einer konischen zu einer <strong>sechseckigen Form wird<\/strong>. Es gibt viele Details, die dessen Stil einzigartig machen; die Kappe aus 3K twill Carbon, die <strong>doppelt genietete<\/strong> umfassende Schelle, die fest gefertigte Eingangsbuchse, um die beste Kupplungsgenauigkeit anzubieten. Auf dem Endschalld\u00e4mpfer erscheint das durch die Laser-Technologie hergestellte typische Mivv Logo.<\/p>\n<p>Das zeichnet sich durch einen K\u00f6rper aus geb\u00fcrstetem Edelstahl mit einem <strong>\u201epearled\u201c<\/strong> Effekt aus; das wird dank eines Sonderverarbeitungsprozesses erreicht, der dem Produkt einen  <strong>einzigartigen Look verleiht.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NUR MIT INSTALLIERTEM KATALYSATOR ACC.076.A1 ZUGELASSEN. Der Einbau dieser Abgasanlage ohne Katalysator und switch-off key kann zum Aufleuchten der Motorwarnleuchte f\u00fchren. Abnehmbarer Katalysator ACC.076.A1 als Option erh\u00e4ltlich<\/p>\n","protected":false},"featured_media":63843,"template":"","meta":{"_acf_changed":false},"product_brand":[21824,21565,21810],"product_cat":[682],"product_tag":[],"class_list":{"0":"post-104572","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-10862","7":"product_brand-aprilia","8":"product_brand-tuono-125","9":"product_cat-komplette-auspuffanlage","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/104572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/63843"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=104572"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=104572"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=104572"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=104572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}