{"id":89935,"date":"2026-04-21T13:22:12","date_gmt":"2026-04-21T11:22:12","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-051-lxb-honda-cb-500-f-x-2013-2015\/"},"modified":"2026-04-21T13:22:12","modified_gmt":"2026-04-21T11:22:12","slug":"h-051-lxb-honda-cb-500-f-x-2013-2015","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/h-051-lxb-honda-cb-500-f-x-2013-2015\/","title":{"rendered":"H.051.LXB &#8211; Honda CB 500 F \/ X 2013 > 2015"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Der GP ist ein <strong>runder, kurzer<\/strong> Schalld\u00e4mpfer mit ausgeweiteten Verschl\u00fcssen; der Auspuff wurde durch die Anwendung der technischen L\u00f6sungen der Wettbewerbsd\u00e4mpfer gefertigt.<\/p>\n<p>Der Zentralk\u00f6rper wurde aus schwarzem Edelstahl mit Effekt  <strong>\u201cBlack Moon\u201d<\/strong> gefertigt. Der Effekt wurde durch ein spezielles Lackierverfahren erzielt. Diese Bearbeitung verleiht dem Produkt einen <strong>aggressiveren<\/strong> Look.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der zur \u00c4sthetik, Sound und Leistungs-Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die sich auch durch den Look seines eigenen Motorrads auszeichnen wollen, zu befriedigen. Der GP ist ein runder, kurzer Schalld\u00e4mpfer mit ausgeweiteten Verschl\u00fcssen; der Auspuff wurde durch die Anwendung der technischen L\u00f6sungen der Wettbewerbsd\u00e4mpfer [&hellip;]<\/p>\n","protected":false},"featured_media":62610,"template":"","meta":{"_acf_changed":false},"product_brand":[23966,23959,23847],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-89935","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2013-2015-cb-500-f-x","7":"product_brand-cb-500-f-x","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/89935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/62610"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=89935"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=89935"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=89935"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=89935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}