{"id":90061,"date":"2026-04-21T13:22:55","date_gmt":"2026-04-21T11:22:55","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-038-l9-honda-hornet-600-2007-2013\/"},"modified":"2026-04-21T13:22:55","modified_gmt":"2026-04-21T11:22:55","slug":"h-038-l9-honda-hornet-600-2007-2013","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/h-038-l9-honda-hornet-600-2007-2013\/","title":{"rendered":"H.038.L9 &#8211; Honda HORNET 600 2007 > 2013"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Die Linie SUONO ist die perfekte Synthese aus <strong>\u00c4sthetik, Innovation<\/strong> und modernster angewandter <strong>Technologie<\/strong>. Bei der Entwicklung des Suono wurden <strong>hochwertigste Materialien <\/strong>verwendet, um ein Maximum an <strong>Gewichtsreduzierung<\/strong> zu erzielen.<\/p>\n<p>Dieser Endschalld\u00e4mpfer wurde durch einen zentralen K\u00f6rper aus schwarzem Edelstahl mit  Effekt <strong>\u201eBlack Moon\u201c<\/strong> hergestellt. Der Effekt wurde durch ein spezielles Lackierverfahren erzielt. Diese Bearbeitung verleiht dem Produkt einen <strong>aggressiveren<\/strong> Look.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der zur \u00c4sthetik, Sound und Leistungs-Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die sich auch durch den Look seines eigenen Motorrads auszeichnen wollen, zu befriedigen. Die Linie SUONO ist die perfekte Synthese aus \u00c4sthetik, Innovation und modernster angewandter Technologie. Bei der Entwicklung des Suono wurden hochwertigste [&hellip;]<\/p>\n","protected":false},"featured_media":62600,"template":"","meta":{"_acf_changed":false},"product_brand":[24533,23847,24505],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-90061","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2007-2013-hornet-600","7":"product_brand-honda","8":"product_brand-hornet-600","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/90061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/62600"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=90061"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=90061"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=90061"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=90061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}