{"id":90257,"date":"2026-04-21T13:24:22","date_gmt":"2026-04-21T11:24:22","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-024-ln-honda-xrv-750-africa-twin-1993-2020\/"},"modified":"2026-04-21T13:24:22","modified_gmt":"2026-04-21T11:24:22","slug":"h-024-ln-honda-xrv-750-africa-twin-1993-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/h-024-ln-honda-xrv-750-africa-twin-1993-2020\/","title":{"rendered":"H.024.LN &#8211; Honda XRV 750 AFRICA TWIN 1993 > 2020"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Der Auspuff OVAL passt sich perfekt jedem Motorrad an. Dieser mit gro\u00dfer Liebe f\u00fcrs Detail entwickelte Endschalld\u00e4mpfer stellt den bestm\u00f6glichen Kompromiss zwischen <strong>Design<\/strong> und <strong>Leistung<\/strong> dar. <\/p>\n<p>Der Endschalld\u00e4mpfer wurde mit K\u00f6rper aus Titan gefertigt; dieses Material verleiht dem Endschalld\u00e4mpfer Leichtigkeit und Exklusivit\u00e4t.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der zur \u00c4sthetik, Sound und Leistungs-Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die sich auch durch den Look seines eigenen Motorrads auszeichnen wollen, zu befriedigen. Der Auspuff OVAL passt sich perfekt jedem Motorrad an. Dieser mit gro\u00dfer Liebe f\u00fcrs Detail entwickelte Endschalld\u00e4mpfer stellt den bestm\u00f6glichen Kompromiss [&hellip;]<\/p>\n","protected":false},"featured_media":62683,"template":"","meta":{"_acf_changed":false},"product_brand":[24946,23847,24939],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-90257","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-1993-2002-xrv-750-africa-twin","7":"product_brand-honda","8":"product_brand-xrv-750-africa-twin","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/90257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/62683"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=90257"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=90257"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=90257"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=90257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}