{"id":90355,"date":"2026-04-21T13:24:56","date_gmt":"2026-04-21T11:24:56","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/r-ho-0002-s8-honda-cbr-1000-rr-2008-2013\/"},"modified":"2026-04-21T13:24:56","modified_gmt":"2026-04-21T11:24:56","slug":"r-ho-0002-s8-honda-cbr-1000-rr-2008-2013","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/r-ho-0002-s8-honda-cbr-1000-rr-2008-2013\/","title":{"rendered":"R.HO.0002.S8 &#8211; Honda CBR 1000 RR 2008 > 2013"},"content":{"rendered":"<p>Die <strong>kompletten Auspuffanlagen<\/strong> stellen das \u201eHighlight\u201c der <strong>Mivv-Technologie<\/strong> dar. Jedes einzelne Produkt wird auf unseren Pr\u00fcfst\u00e4nden getestet, wobei der Motorleistung besondere Aufmerksamkeit gilt um die bestm\u00f6gliche <strong>Performance<\/strong> zu erzielen.<\/p>\n<p>Die <strong>EVO<\/strong> Linie, die f\u00fcr die Racing Welt bestimmt ist, ist die <strong>pr\u00e4chtige Linie<\/strong> der Mivv kompletten Auspuffsysteme. Die wurde entwickelt, um die Anforderungen der verschiedenen <strong>Teams<\/strong> im Rennsport zu erf\u00fcllen. Die Version Evo wurde u.a. mit in der MotoGP gesammelten Erfahrungen entwickelt und wird komplett aus <strong>Titan<\/strong> Grad 1 hergestellt. S\u00e4mtliche Schwei\u00dfverbindungen der einzelnen Komponenten wurden ausschlie\u00dflich mit dem TIG-Verfahren hergestellt.<\/p>\n<p>Die <strong>Vorteile<\/strong> unserer kompletten Auspuffanlagen: Maximum an <strong>Leistung<\/strong>; Materialien mit h\u00f6chster Zuverl\u00e4ssigkeit; <strong>Gewichtsersparnis; Einfache<\/strong> Montage.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die kompletten Auspuffanlagen stellen das \u201eHighlight\u201c der Mivv-Technologie dar. Jedes einzelne Produkt wird auf unseren Pr\u00fcfst\u00e4nden getestet, wobei der Motorleistung besondere Aufmerksamkeit gilt um die bestm\u00f6gliche Performance zu erzielen. Die EVO Linie, die f\u00fcr die Racing Welt bestimmt ist, ist die pr\u00e4chtige Linie der Mivv kompletten Auspuffsysteme. Die wurde entwickelt, um die Anforderungen der verschiedenen [&hellip;]<\/p>\n","protected":false},"featured_media":25079,"template":"","meta":{"_acf_changed":false},"product_brand":[24106,24085,23847],"product_cat":[980],"product_tag":[],"class_list":{"0":"post-90355","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2008-2013-cbr-1000-rr","7":"product_brand-cbr-1000-rr","8":"product_brand-honda","9":"product_cat-komplette-auspuffanlage-evo","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/90355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/25079"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=90355"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=90355"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=90355"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=90355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}