{"id":93428,"date":"2026-04-21T13:45:25","date_gmt":"2026-04-21T11:45:25","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-026-lrx-bmw-r-1200-r-2015-2018\/"},"modified":"2026-04-21T13:45:25","modified_gmt":"2026-04-21T11:45:25","slug":"b-026-lrx-bmw-r-1200-r-2015-2018","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/b-026-lrx-bmw-r-1200-r-2015-2018\/","title":{"rendered":"B.026.LRX &#8211; BMW R 1200 R 2015 > 2018"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p><strong>Modernes Design<\/strong> und ausgezeichnete Leistung sind die Hauptmerkmale des SPEED EDGE Auspuffs; hinzu kommt ein deutlich sportlicher Sound.<\/p>\n<p>Der Auspuff wurde mit K\u00f6rper aus <strong>geb\u00fcrstetem Edelstahl<\/strong> und mit Kappe und Befestigungsschelle aus <strong>Carbon<\/strong> gefertigt; der Auspuff hat eine <strong>sechseckige<\/strong> Form. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der zur \u00c4sthetik, Sound und Leistungs-Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die sich auch durch den Look seines eigenen Motorrads auszeichnen wollen, zu befriedigen. Modernes Design und ausgezeichnete Leistung sind die Hauptmerkmale des SPEED EDGE Auspuffs; hinzu kommt ein deutlich sportlicher Sound. Der Auspuff wurde [&hellip;]<\/p>\n","protected":false},"featured_media":63230,"template":"","meta":{"_acf_changed":false},"product_brand":[22426,22104,22412],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-93428","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2015-2018-r-1200-r","7":"product_brand-bmw","8":"product_brand-r-1200-r","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/93428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/63230"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=93428"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=93428"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=93428"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=93428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}