{"id":95290,"date":"2026-04-21T13:58:26","date_gmt":"2026-04-21T11:58:26","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-031-l6p-bmw-s-1000-rr-2017-2018\/"},"modified":"2026-04-21T13:58:26","modified_gmt":"2026-04-21T11:58:26","slug":"b-031-l6p-bmw-s-1000-rr-2017-2018","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/b-031-l6p-bmw-s-1000-rr-2017-2018\/","title":{"rendered":"B.031.L6P &#8211; BMW S 1000 RR 2017 > 2018"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Das GP PRO zeigt eine <strong>TIG-halb handgefertigte Schwei\u00dfung<\/strong>, ein Kompaktes und <strong>wesentliches Design und einen aggressiven Sound<\/strong> auf. Das von der <strong>Wettbewerbswelt<\/strong> inspirierte Ausgangsauspuffrohr ist mit einer <strong>abnehmbaren Schutzgitter<\/strong> ausgestattet, die den dB-killer verbirgt. Auf dem Endschalld\u00e4mpfer erscheint das durch die Laser-Technologie hergestellte typische Mivv Logo.<\/p>\n<p>Das zeichnet sich durch einen Hauptk\u00f6rper aus <strong>Titan<\/strong> mit einem \u201epearled\u201c Effekt aus, der dank eines Sonderverarbeitungsprozesses erreicht wurde. Das ist der ideale Auspuff f\u00fcr diejenigen, die ein <strong>exklusives Produkt<\/strong> w\u00fcnschen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der zur \u00c4sthetik, Sound und Leistungs-Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die sich auch durch den Look seines eigenen Motorrads auszeichnen wollen, zu befriedigen. Das GP PRO zeigt eine TIG-halb handgefertigte Schwei\u00dfung, ein Kompaktes und wesentliches Design und einen aggressiven Sound auf. Das von der [&hellip;]<\/p>\n","protected":false},"featured_media":63762,"template":"","meta":{"_acf_changed":false},"product_brand":[22531,22104,22524],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-95290","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2017-2018-s-1000-rr","7":"product_brand-bmw","8":"product_brand-s-1000-rr","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/95290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/63762"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=95290"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=95290"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=95290"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=95290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}