{"id":95584,"date":"2026-04-21T14:00:28","date_gmt":"2026-04-21T12:00:28","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/e-003-l3c-benelli-trk-502-2017-2024\/"},"modified":"2026-04-21T14:00:28","modified_gmt":"2026-04-21T12:00:28","slug":"e-003-l3c-benelli-trk-502-2017-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/e-003-l3c-benelli-trk-502-2017-2024\/","title":{"rendered":"E.003.L3C- BENELLI TRK 502 2017 > 2024"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Der Auspuff OVAL passt sich perfekt jedem Motorrad an. Dieser mit gro\u00dfer Liebe f\u00fcrs Detail entwickelte Endschalld\u00e4mpfer stellt den bestm\u00f6glichen Kompromiss zwischen <strong>Design<\/strong> und <strong>Leistung<\/strong> dar. <\/p>\n<p>Der Auspuff zeichnet sich durch K\u00f6rper und Kappe aus <strong>Carbon<\/strong> aus, die hitzebest\u00e4ndig sind. Der Auspuff hat ge\u00f6ffnete Schlitze auf der kappe, einem Detail, welches dem Endschalld\u00e4mpfer ein <strong>sportlicheres<\/strong> Design verleiht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zur Leistungsverbesserung empfehlen wir ein neues Mapping des Steuerger\u00e4ts. Zur weiteren Info lesen Sie die technische Beschreibung unter dem Doku-K\u00e4stchen.<\/p>\n","protected":false},"featured_media":62642,"template":"","meta":{"_acf_changed":false},"product_brand":[22048,21916,22041],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-95584","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2017-trk-502","7":"product_brand-benelli","8":"product_brand-trk-502","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/95584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/62642"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=95584"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=95584"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=95584"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=95584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}