{"id":95654,"date":"2026-04-21T14:01:00","date_gmt":"2026-04-21T12:01:00","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-033-sdrx-ducati-multistrada-1260-2018-2020\/"},"modified":"2026-04-21T14:01:00","modified_gmt":"2026-04-21T12:01:00","slug":"d-033-sdrx-ducati-multistrada-1260-2018-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/d-033-sdrx-ducati-multistrada-1260-2018-2020\/","title":{"rendered":"D.033.SDRX \u2013 DUCATI MULTISTRADA 1260 2018 > 2020"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Der DELTA RACE Auspuff zeichnet sich durch eine <strong>exklusive Form<\/strong> aus, die mittels einer allm\u00e4hlichen Umwandlung von einer konischen zu einer <strong>sechseckigen Form wird<\/strong>. Es gibt viele Details, die dessen Stil einzigartig machen; die Kappe aus 3K twill Carbon, die <strong>doppelt genietete<\/strong> umfassende Schelle, die fest gefertigte Eingangsbuchse, um die beste Kupplungsgenauigkeit anzubieten. Auf dem Endschalld\u00e4mpfer erscheint das durch die Laser-Technologie hergestellte typische Mivv Logo.<\/p>\n<p>Das zeichnet sich durch einen K\u00f6rper aus geb\u00fcrstetem Edelstahl mit einem <strong>\u201epearled\u201c<\/strong> Effekt aus; das wird dank eines Sonderverarbeitungsprozesses erreicht, der dem Produkt einen  <strong>einzigartigen Look verleiht.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Einbau dieses Auspuffs erfordert das Remapping der ECU. Weitere Informationen finden Sie in den technischen Informationen unter der Dokumentationsbox.<\/p>\n","protected":false},"featured_media":63843,"template":"","meta":{"_acf_changed":false},"product_brand":[23308,22769,23301],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-95654","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2018-multistrada-1260","7":"product_brand-ducati","8":"product_brand-multistrada-1260","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/95654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/63843"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=95654"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=95654"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=95654"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=95654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}