{"id":95962,"date":"2026-04-21T14:03:20","date_gmt":"2026-04-21T12:03:20","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-041-sm3c-ducati-monster-1200-2017-2021\/"},"modified":"2026-04-21T14:03:20","modified_gmt":"2026-04-21T12:03:20","slug":"d-041-sm3c-ducati-monster-1200-2017-2021","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/d-041-sm3c-ducati-monster-1200-2017-2021\/","title":{"rendered":"D.041.SM3C \u2013 DUCATI MONSTER 1200 2017 > 2021"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Die <strong> MK3<\/strong> Linie , die das Ergebnis der in den <strong> Moto3 und Moto2<\/strong> Weltmeisterschaften gesammelten Erfahrung ist, ist die perfekte Synthese zwischen <strong>Leistung und Technologie<\/strong>. Mit einem <strong>Design<\/strong>, das den <strong>Motorradweltmeisterschaft MK3<\/strong> Auspuffen \u00e4hnlich ist, ist ein Produkt mit <strong>kompakten<\/strong> Ausmessungen, das den gewinnenden <strong>MIVV- Sound ausstr\u00f6men kann.<\/strong><\/p>\n<p>Die carbon-Ausf\u00fchrung besitzt eine H\u00fclle aus <strong>hochgl\u00e4nzendem\u00a0carbon<\/strong>, der zusammen mit dem Gitter an der Endkappe, dem Produkt einen <strong>\u201ehigh tech\u201c Look verleiht<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der zur \u00c4sthetik, Sound und Leistungs-Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die sich auch durch den Look seines eigenen Motorrads auszeichnen wollen, zu befriedigen. Die MK3 Linie , die das Ergebnis der in den Moto3 und Moto2 Weltmeisterschaften gesammelten Erfahrung ist, ist die perfekte Synthese [&hellip;]<\/p>\n","protected":false},"featured_media":64181,"template":"","meta":{"_acf_changed":false},"product_brand":[23035,22769,23028],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-95962","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2017-monster-1200","7":"product_brand-ducati","8":"product_brand-monster-1200","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/95962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/64181"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=95962"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=95962"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=95962"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=95962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}