{"id":96201,"date":"2026-04-21T14:05:02","date_gmt":"2026-04-21T12:05:02","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-030-ldrb-ducati-monster-1200-s-2014-2016\/"},"modified":"2026-04-21T14:05:02","modified_gmt":"2026-04-21T12:05:02","slug":"d-030-ldrb-ducati-monster-1200-s-2014-2016","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/d-030-ldrb-ducati-monster-1200-s-2014-2016\/","title":{"rendered":"D.030.LDRB- DUCATI MONSTER 1200 \/ S  2014 > 2016"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Der DELTA RACE Auspuff zeichnet sich durch eine <strong>exklusive Form<\/strong> aus, die mittels einer allm\u00e4hlichen Umwandlung von einer konischen zu einer <strong>sechseckigen Form wird<\/strong>. Es gibt viele Details, die dessen Stil einzigartig machen; die Kappe aus 3K twill Carbon, die <strong>doppelt genietete<\/strong> umfassende Schelle, die fest gefertigte Eingangsbuchse, um die beste Kupplungsgenauigkeit anzubieten. Auf dem Endschalld\u00e4mpfer erscheint das durch die Laser-Technologie hergestellte typische Mivv Logo.<\/p>\n<p>Das zeichnet sich durch einen Zentralk\u00f6rper aus schwarzem Edelstahl mit einem <strong>\u201cBlack Moon\u201c<\/strong>-Effekt aus. Das wird dank eines Sonderlackierungsprozesses mit Keramik erreicht, der dem Produkt einen <strong>aggressiveren Look verleiht.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der zur \u00c4sthetik, Sound und Leistungs-Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die sich auch durch den Look seines eigenen Motorrads auszeichnen wollen, zu befriedigen. Der DELTA RACE Auspuff zeichnet sich durch eine exklusive Form aus, die mittels einer allm\u00e4hlichen Umwandlung von einer konischen zu einer [&hellip;]<\/p>\n","protected":false},"featured_media":63736,"template":"","meta":{"_acf_changed":false},"product_brand":[23049,22769,23042],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-96201","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2014-2016-monster-1200-s","7":"product_brand-ducati","8":"product_brand-monster-1200-s","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/96201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/63736"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=96201"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=96201"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=96201"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=96201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}