{"id":96865,"date":"2026-04-21T14:10:38","date_gmt":"2026-04-21T12:10:38","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-070-lrb-honda-cbr-1000-rr-2017-2019\/"},"modified":"2026-04-21T14:10:38","modified_gmt":"2026-04-21T12:10:38","slug":"h-070-lrb-honda-cbr-1000-rr-2017-2019","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/h-070-lrb-honda-cbr-1000-rr-2017-2019\/","title":{"rendered":"H.070.LRB &#8211; HONDA CBR 1000 RR 2017 > 2019"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p><strong>Modernes Design<\/strong> und ausgezeichnete Leistung sind die Hauptmerkmale des SPEED EDGE Auspuffs; hinzu kommt ein deutlich sportlicher Sound.<\/p>\n<p>Der Auspuff hat Kappe und Befestigungsschelle aus <strong>Carbon<\/strong>; der Zentralk\u00f6rper wurde aus schwarzem Edelstahl mit einem \u201e<strong>Black Moon<\/strong>\u201c-Effekt gefertigt. Das verleiht dem Produkt einen aggressiven <strong>Look<\/strong>. Der Auspuff hat eine <strong>sechseckige<\/strong> Form.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der zur \u00c4sthetik, Sound und Leistungs-Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die sich auch durch den Look seines eigenen Motorrads auszeichnen wollen, zu befriedigen. Modernes Design und ausgezeichnete Leistung sind die Hauptmerkmale des SPEED EDGE Auspuffs; hinzu kommt ein deutlich sportlicher Sound. Der Auspuff hat [&hellip;]<\/p>\n","protected":false},"featured_media":62659,"template":"","meta":{"_acf_changed":false},"product_brand":[24113,24085,23847],"product_cat":[699],"product_tag":[],"class_list":{"0":"post-96865","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2017-2019-cbr-1000-rr","7":"product_brand-cbr-1000-rr","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/96865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/62659"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=96865"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=96865"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=96865"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=96865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}