{"id":98307,"date":"2026-04-21T14:22:32","date_gmt":"2026-04-21T12:22:32","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-077-l6p-honda-cb-125-r-2021-2024\/"},"modified":"2026-04-21T14:22:32","modified_gmt":"2026-04-21T12:22:32","slug":"h-077-l6p-honda-cb-125-r-2021-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/de\/product\/h-077-l6p-honda-cb-125-r-2021-2024\/","title":{"rendered":"H.077.L6P \u2013 HONDA CB 125 R 2021 > 2024"},"content":{"rendered":"<p>Der zur <strong>\u00c4sthetik, Sound und Leistungs-<\/strong>Verbesserungdes Motorrads hergestellte Mivv slip-on, entsteht aus h\u00f6chster Acht auf das Design, mit dem Ziel alle, die <strong>sich<\/strong> auch durch den Look seines eigenen Motorrads <strong>auszeichnen<\/strong> wollen, zu befriedigen.<\/p>\n<p>Das GP PRO zeigt eine <strong>TIG-halb handgefertigte Schwei\u00dfung<\/strong>, ein Kompaktes und <strong>wesentliches Design und einen aggressiven Sound<\/strong> auf. Das von der <strong>Wettbewerbswelt<\/strong> inspirierte Ausgangsauspuffrohr ist mit einer <strong>abnehmbaren Schutzgitter<\/strong> ausgestattet, die den dB-killer verbirgt. Auf dem Endschalld\u00e4mpfer erscheint das durch die Laser-Technologie hergestellte typische Mivv Logo.<\/p>\n<p>Das zeichnet sich durch einen Hauptk\u00f6rper aus <strong>Titan<\/strong> mit einem \u201epearled\u201c Effekt aus, der dank eines Sonderverarbeitungsprozesses erreicht wurde. Das ist der ideale Auspuff f\u00fcr diejenigen, die ein <strong>exklusives Produkt<\/strong> w\u00fcnschen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EURO 5 Zulassung nur wenn Nachr\u00fcstkat ACC.073.A1 montiert wird. NICHT KOMPATIBEL MIT EURO 5+ FAHRZEUGEN, DIE MIT EINER LAMBDASONDE NACH DEM KATALYSATOR AUSGESTATTET SIND.<\/p>\n","protected":false},"featured_media":63762,"template":"","meta":{"_acf_changed":false},"product_brand":[23931,23917,23847],"product_cat":[682],"product_tag":[],"class_list":{"0":"post-98307","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2021-cb-125-r","7":"product_brand-cb-125-r","8":"product_brand-honda","9":"product_cat-komplette-auspuffanlage","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product\/98307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media\/63762"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/media?parent=98307"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_brand?post=98307"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_cat?post=98307"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/de\/wp-json\/wp\/v2\/product_tag?post=98307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}