{"id":1074,"date":"2026-02-03T17:29:35","date_gmt":"2026-02-03T16:29:35","guid":{"rendered":"http:\/\/mivv2026.local\/mivv-customer-support\/after-sales-support\/"},"modified":"2026-02-16T17:38:32","modified_gmt":"2026-02-16T16:38:32","slug":"after-sales-support","status":"publish","type":"page","link":"https:\/\/dev.mivv.com\/en\/mivv-customer-support\/after-sales-support\/","title":{"rendered":"After-Sales Support"},"content":{"rendered":"\n<div class=\"wp-block-columns sezione-faq-assistenza is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\">\n<h2 class=\"wp-block-heading\">Technical Information<\/h2>\n\n\n\n<p>Download the official MIVV Technical Information booklet in PDF format. It contains essential information on homologation, maintenance, and safety.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-black-background-color has-text-color has-background has-link-color wp-element-button\" href=\"\/wp-content\/uploads\/2026\/02\/libretto-istruzioni-prodotti-mivv.pdf\" style=\"border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-left-radius:0px;border-bottom-right-radius:0px\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Download the PDF<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Submit a Support Request<\/h2>\n\n<p>Fill out the form below, providing as much detail as possible. Images are essential to allow our technicians to properly assess your situation.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Please remember to have the product code handy to speed up the process.<\/p>\n<\/blockquote>\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f86134-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"86134\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/1074#wpcf7-f86134-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"86134\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f86134-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"mivv-form-post-vendita\">\n\t<fieldset>\n\t\t<legend>Customer and Product Details\n\t\t<\/legend>\n\t\t<div class=\"mivv-grid-half\">\n\t\t\t<p><label for=\"post-nome\"> First Name <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"post-nome\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E.g.: Mario\" value=\"\" type=\"text\" name=\"post-first-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"mivv-grid-half\">\n\t\t\t<p><label for=\"post-cognome\"> Last Name <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" id=\"post-cognome\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E.g.: Rossi\" value=\"\" type=\"text\" name=\"post-last-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"mivv-grid-half\">\n\t\t\t<p><label for=\"post-email\"> Email <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" id=\"post-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"email@example.com\" value=\"\" type=\"email\" name=\"post-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"mivv-grid-half\">\n\t\t\t<p><label for=\"post-codice\"> Product Code <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-codice\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"post-codice\" aria-invalid=\"false\" placeholder=\"E.g.: H.044.LXB\" value=\"\" type=\"text\" name=\"post-codice\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"mivv-grid-full\">\n\t\t\t<p><label for=\"post-tipo\"> Type of issue <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-tipo\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" id=\"post-tipo\" aria-required=\"true\" aria-invalid=\"false\" name=\"post-tipo\"><option value=\"\">&#8212;Please choose an option&#8212;<\/option><option value=\"Assembly difficulties\">Assembly difficulties<\/option><option value=\"Missing components\">Missing components<\/option><option value=\"Aesthetic\/quality issue\">Aesthetic\/quality issue<\/option><option value=\"Homologation\/Certificates\">Homologation\/Certificates<\/option><option value=\"Other\">Other<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/fieldset>\n\t<fieldset>\n\t\t<legend>Issue Details\n\t\t<\/legend>\n\t\t<div class=\"mivv-grid-full\">\n\t\t\t<p><label for=\"post-messaggio\"> Detailed description <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-message\"><textarea cols=\"40\" rows=\"5\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" id=\"post-messaggio\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Describe the issue you encountered...\" name=\"post-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"mivv-grid-full\">\n\t\t\t<div class=\"upload-container\">\n\t\t\t\t<p><label class=\"upload-box\" for=\"post-file\"><br \/>\n<span>Upload a photo of the issue (max 2MB)<\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"post-file\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.jpeg,.png,.pdf\" aria-invalid=\"false\" type=\"file\" name=\"post-file\" \/><\/span><br \/>\n<\/label>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/fieldset>\n\t<div class=\"mivv-form-footer\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"privacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"privacy\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I accept the Privacy Policy<\/span><\/label><\/span><\/span><\/span><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-dark\" type=\"submit\" value=\"Submit Report\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Technical Information Download the official MIVV Technical Information booklet in PDF format. It contains essential information on homologation, maintenance, and safety. Submit a Support Request Fill out the form below, providing as much detail as possible. Images are essential to allow our technicians to properly assess your situation. Please remember to have the product code [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":1038,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1074","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/en\/wp-json\/wp\/v2\/pages\/1074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.mivv.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/en\/wp-json\/wp\/v2\/comments?post=1074"}],"version-history":[{"count":1,"href":"https:\/\/dev.mivv.com\/en\/wp-json\/wp\/v2\/pages\/1074\/revisions"}],"predecessor-version":[{"id":1075,"href":"https:\/\/dev.mivv.com\/en\/wp-json\/wp\/v2\/pages\/1074\/revisions\/1075"}],"up":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/en\/wp-json\/wp\/v2\/pages\/1038"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/en\/wp-json\/wp\/v2\/media?parent=1074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}