{"id":101381,"date":"2026-04-21T14:49:03","date_gmt":"2026-04-21T12:49:03","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-091-lh1bc-honda-cmx-500-rebel-2022-2024\/"},"modified":"2026-04-21T14:49:03","modified_gmt":"2026-04-21T12:49:03","slug":"h-091-lh1bc-honda-cmx-500-rebel-2022-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/h-091-lh1bc-honda-cmx-500-rebel-2022-2024\/","title":{"rendered":"H.091.LH1BC &#8211; HONDA CMX 500 REBEL 2022 > 2024"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>Los escapes de la l\u00ednea HR-1 tienen una forma redonda y est\u00e1n montados con remaches negros que tienen un <strong>look especial<\/strong>. La copa de salida ser\u00e1 de <strong>aluminio cer\u00e1mico pintado negro<\/strong> o de <strong>carbono \u00abtwill 3k look\u00bb<\/strong><\/p>\n<p>Se caracteriza por un cuerpo central de acero inox negro con efecto <strong>\u201cBlack Moon\u201d<strong>, que se obtiene gracias a un proceso especial de pintura con base cer\u00e1mica. Esto da al producto un <strong>look \u00abclassic style\u00bb<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. Los escapes de la l\u00ednea HR-1 tienen una forma redonda y est\u00e1n montados con [&hellip;]<\/p>\n","protected":false},"featured_media":65917,"template":"","meta":{"_acf_changed":false},"product_brand":[24345,24338,23848],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-101381","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2022-cmx-500-rebel","7":"product_brand-cmx-500-rebel","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/101381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/65917"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=101381"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=101381"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=101381"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=101381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}