{"id":101675,"date":"2026-04-21T14:51:39","date_gmt":"2026-04-21T12:51:39","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/acc-041-a1-voge-brivido-125-r-2023-2024\/"},"modified":"2026-04-21T14:51:39","modified_gmt":"2026-04-21T12:51:39","slug":"acc-041-a1-voge-brivido-125-r-2023-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/acc-041-a1-voge-brivido-125-r-2023-2024\/","title":{"rendered":"ACC.041.A1 &#8211; VOGE BRIVIDO 125 R 2023 > 2024"},"content":{"rendered":"<p>Mivv utiliza catalizadores met\u00e1licos con el fin de garantizar a tu moto una mejor\u00eda de las performance y del sound.<br \/>\n\u00c9stos catalizadores est\u00e1n estudiados para obtener una adecuada disminuci\u00f3n de los gases contaminantes convirtiendo el escape en versi\u00f3n homologada seg\u00fan las normativas vigentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mivv utiliza catalizadores met\u00e1licos con el fin de garantizar a tu moto una mejor\u00eda de las performance y del sound. \u00c9stos catalizadores est\u00e1n estudiados para obtener una adecuada disminuci\u00f3n de los gases contaminantes convirtiendo el escape en versi\u00f3n homologada seg\u00fan las normativas vigentes.<\/p>\n","protected":false},"featured_media":63272,"template":"","meta":{"_acf_changed":false},"product_brand":[28636,28627,28625],"product_cat":[691],"product_tag":[],"class_list":{"0":"post-101675","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2023-brivido-125-r","7":"product_brand-brivido-125-r","8":"product_brand-voge","9":"product_cat-catalizador","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/101675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/63272"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=101675"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=101675"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=101675"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=101675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}