{"id":102123,"date":"2026-04-21T14:55:28","date_gmt":"2026-04-21T12:55:28","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-093-lxbp-honda-cb-500-hornet-2024-2026\/"},"modified":"2026-04-21T14:55:28","modified_gmt":"2026-04-21T12:55:28","slug":"h-093-lxbp-honda-cb-500-hornet-2024-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/h-093-lxbp-honda-cb-500-hornet-2024-2026\/","title":{"rendered":"H.093.LXBP &#8211; HONDA CB 500 HORNET 2024 > 2026"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>GP PRO tiene una <strong>soldadura a TIG semiartesanal<\/strong>, un <strong>dise\u00f1o compacto<\/strong> y esencial y un <strong>sonido agresivo<\/strong>. El tubo de salida gracias a la inspiraci\u00f3n del mundo de las <strong>competiciones<\/strong> est\u00e1 equipado con una <strong>reja de protecci\u00f3n removible<\/strong> que esconde el dB-killer. En el terminal est\u00e1 el caracteristico logo Mivv realizado por la tecnolog\u00eda Laser.<\/p>\n<p>Se caracteriza por un cuerpo central de acero inox negro con efecto cepillado <strong>\u201cBlack Moon\u201d<\/strong>, obtenido por un proceso de coloraci\u00f3n especial. Esta versi\u00f3n da al producto un <strong>aspecto m\u00e1s agresivo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La instalaci\u00f3n de este sistema de escape sin la switch-off key puede provocar que se encienda la luz de advertencia del motor<\/p>\n","protected":false},"featured_media":63719,"template":"","meta":{"_acf_changed":false},"product_brand":[23981,23974,23848],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-102123","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2024-2026-11261","7":"product_brand-cb-500-hornet","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/102123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/63719"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=102123"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=102123"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=102123"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=102123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}