{"id":102410,"date":"2026-04-21T14:58:10","date_gmt":"2026-04-21T12:58:10","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-038-lc4t-bmw-f-900-r-2025-2026\/"},"modified":"2026-04-21T14:58:10","modified_gmt":"2026-04-21T12:58:10","slug":"b-038-lc4t-bmw-f-900-r-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/b-038-lc4t-bmw-f-900-r-2025-2026\/","title":{"rendered":"B.038.LC4T \u2013 BMW F 900 R 2025 > 2026"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>La l\u00ednea <strong>X-M1<\/strong>,  es el resultado de la experiencia conseguida en los campeonatos mundiales <strong>MotoGP y Moto2<\/strong>, es la s\u00edntesi perfecta entre las <strong>prestaciones<\/strong> y el <strong>estilo racing<\/strong>. Con un <strong>dise\u00f1o<\/strong> parecido a los escapes fabricados para el Campeonato del Mundo de Motociclismo , el escape <strong>X-M1<\/strong> ofrece una forma <strong>c\u00f3nica<\/strong> y  dimensiones <strong>compactas<\/strong> capaces de desarrollar el agradable <strong>sonido<\/strong> MIVV. <\/p>\n<p>La versi\u00f3n <strong>Titanium<\/strong> se caracteriza por un cuerpo central de titanio grado 1 Slow con un efecto <strong>\u201cpearled\u201d<\/strong> obtenido por medio de un proceso especial de fabricaci\u00f3n. Esta es la versi\u00f3n perfecta para aquellos, que quieren conseguir  una enorme  disminuci\u00f3n de <strong>peso<\/strong>.  <\/p>\n<p><strong>X-M1 puro estilo italiano.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compatible solo con las bolsas laterales originales<\/p>\n","protected":false},"featured_media":7840,"template":"","meta":{"_acf_changed":false},"product_brand":[22252,22105,22238],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-102410","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-9375","7":"product_brand-bmw","8":"product_brand-f-900-r","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/102410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/7840"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=102410"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=102410"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=102410"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=102410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}