{"id":103509,"date":"2026-04-21T15:08:14","date_gmt":"2026-04-21T13:08:14","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-044-lrb-bmw-f-800-gs-2024-2024\/"},"modified":"2026-04-21T15:08:14","modified_gmt":"2026-04-21T13:08:14","slug":"b-044-lrb-bmw-f-800-gs-2024-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/b-044-lrb-bmw-f-800-gs-2024-2024\/","title":{"rendered":"B.044.LRB &#8211; BMW F 800 GS 2024 > 2024"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p><strong>Dise\u00f1o moderno<\/strong> y prestaciones excelentes son las principales caracter\u00edsticas del escape SPEED EDGE, a las que se une un <strong>sound<\/strong> claramente <strong>deportivo<\/strong>.<\/p>\n<p>Con tapa y abrazadera de anclaje de <strong>carbono<\/strong>, el cuerpo central est\u00e1 fabricado en acero inox <strong>negro \u201cBlack Moon\u201d<\/strong> y da al producto un <strong>look<\/strong> agresivo. El escape tiene una forma <strong>hexagonal<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. Dise\u00f1o moderno y prestaciones excelentes son las principales caracter\u00edsticas del escape SPEED EDGE, a [&hellip;]<\/p>\n","protected":false},"featured_media":62659,"template":"","meta":{"_acf_changed":false},"product_brand":[22168,22105,22154],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-103509","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2024-f-800-gs","7":"product_brand-bmw","8":"product_brand-f-800-gs","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/103509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/62659"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=103509"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=103509"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=103509"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=103509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}