{"id":103600,"date":"2026-04-21T15:08:56","date_gmt":"2026-04-21T13:08:56","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-087-ldkb-honda-xl750-transalp-2025-2026\/"},"modified":"2026-04-21T15:08:56","modified_gmt":"2026-04-21T13:08:56","slug":"h-087-ldkb-honda-xl750-transalp-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/h-087-ldkb-honda-xl750-transalp-2025-2026\/","title":{"rendered":"H.087.LDKB \u2013 HONDA XL750 TRANSALP 2025 > 2026"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>El projecto del escape Dakar es el fruto de la experiencia del nuestro departimiento R&#038;D en el sector de las <strong>competiciones rally<\/strong>.<\/p>\n<p>El resultado es un <strong>escape simple pero robusto<\/strong>, que es perfecto para los que  prediligen hacer una carrera off road m\u00e0s <strong>exigente<\/strong>.<\/p>\n<p>La versi\u00f3n\u00a0<strong>black<\/strong>\u00a0se caracteriza por un cuerpo central de acero inox <strong>negro<\/strong> 304 con efecto\u00a0<strong>\u00abBlack Moon\u00bb<\/strong>\u00a0obtenido por medio de un proceso especial de pintura con <strong>ceramica<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NO COMPATIBLE CON LA MALETA LATERAL DERECHA<\/p>\n","protected":false},"featured_media":64431,"template":"","meta":{"_acf_changed":false},"product_brand":[24898,23848,24884],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-103600","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-10818","7":"product_brand-honda","8":"product_brand-xl-750-transalp","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/103600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/64431"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=103600"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=103600"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=103600"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=103600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}