{"id":103761,"date":"2026-04-21T15:10:44","date_gmt":"2026-04-21T13:10:44","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/e-012-lx2c-benelli-trk-702-x-2025-2026\/"},"modified":"2026-04-21T15:10:44","modified_gmt":"2026-04-21T13:10:44","slug":"e-012-lx2c-benelli-trk-702-x-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/e-012-lx2c-benelli-trk-702-x-2025-2026\/","title":{"rendered":"E.012.LX2C- BENELLI TRK 702 \/ X 2025 > 2026"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>Los escapes de la l\u00ednea OVAL se adaptan perfectamente a todo tipo de motos. Acabado con gran atenci\u00f3n al detalle, es una l\u00ednea que representa el mejor compromiso entre el <strong>dise\u00f1o<\/strong> y el <strong>rendimiento<\/strong>. <\/p>\n<p>El escape est\u00e1 realizado por el cuerpo en acero inox <strong>cepillado<\/strong>; este material da al escape el cl\u00e1sico <strong>aspecto natural<\/strong> del acero inox.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. Los escapes de la l\u00ednea OVAL se adaptan perfectamente a todo tipo de motos. [&hellip;]<\/p>\n","protected":false},"featured_media":7189,"template":"","meta":{"_acf_changed":false},"product_brand":[22098,21917,22084],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-103761","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-11161","7":"product_brand-benelli","8":"product_brand-trk-702-x","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/103761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/7189"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=103761"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=103761"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=103761"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=103761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}