{"id":104454,"date":"2026-04-21T15:16:49","date_gmt":"2026-04-21T13:16:49","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/acc-101-0-honda-forza-750-2025-2026\/"},"modified":"2026-04-21T15:16:49","modified_gmt":"2026-04-21T13:16:49","slug":"acc-101-0-honda-forza-750-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/acc-101-0-honda-forza-750-2025-2026\/","title":{"rendered":"ACC.101.0 &#8211; HONDA FORZA 750 2025 > 2026"},"content":{"rendered":"<p><p>MIVV SWITCH OFF KEY es un dispositivo electr&oacute;nico plug and play de autodiagn&oacute;stico (OBD) para motocicletas Euro5+ que cuenta con las siguientes funciones:<\/p>\n<ul>\n<li>Apaga la luz de aver&iacute;a del motor (Check Engine) en los casos en que se encienda debido a la sustituci&oacute;n del catalizador original por un modelo de recambio, lo que puede provocar alteraciones en los par&aacute;metros de ox&iacute;geno con respecto a los preestablecidos por la configuraci&oacute;n de la centralita original.<\/li>\n<li>La inhibici&oacute;n del encendido de la luz Check Engine conserva, al mismo tiempo, el funcionamiento correcto del diagn&oacute;stico a bordo.<\/li>\n<li>No interviene de ninguna manera en la programaci&oacute;n original de la centralita del motor ni en otros par&aacute;metros electr&oacute;nicos del veh&iacute;culo.<\/li>\n<\/ul>\n<p>Producto no homologado.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MIVV SWITCH OFF KEY es un dispositivo electr&oacute;nico plug and play de autodiagn&oacute;stico (OBD) para motocicletas Euro5+ que cuenta con las siguientes funciones: Apaga la luz de aver&iacute;a del motor (Check Engine) en los casos en que se encienda debido a la sustituci&oacute;n del catalizador original por un modelo de recambio, lo que puede provocar [&hellip;]<\/p>\n","protected":false},"featured_media":5898,"template":"","meta":{"_acf_changed":false},"product_brand":[24499,24485,23848],"product_cat":[832],"product_tag":[],"class_list":{"0":"post-104454","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-10378","7":"product_brand-forza-750","8":"product_brand-honda","9":"product_cat-llave-de-desactivacion","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/104454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/5898"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=104454"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=104454"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=104454"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=104454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}