{"id":104615,"date":"2026-04-21T15:18:18","date_gmt":"2026-04-21T13:18:18","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/a-022-kdrb-aprilia-tuono-125-2025-2026\/"},"modified":"2026-04-21T15:18:18","modified_gmt":"2026-04-21T13:18:18","slug":"a-022-kdrb-aprilia-tuono-125-2025-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/a-022-kdrb-aprilia-tuono-125-2025-2026\/","title":{"rendered":"A.022.KDRB- APRILIA TUONO 125 2025 > 2026"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>El escape DELTA RACE se caracteriza por una <strong> forma exclusiva<\/strong>  que, a trav\u00e9s de una transformaci\u00f3n gradual se hace de forma c\u00f3nica a <strong>hexagonal<\/strong> . Hay muchos detalles que hacen el estilo \u00fanico, como la tapa en carbono twill 3K; la abrazadera perimetral con <strong>doble remachado<\/strong> ; el casquillo de entrada fabricado solidamente, para ofrecer la maxima precisi\u00f3n de enganche. En el terminal est\u00e1 el caracteristico logo Mivv realizado por la tecnolog\u00eda Laser.<\/p>\n<p>Se caracteriza por un cuerpo central de acero inox negro con efecto <strong>\u201cBlack Moon\u201d<\/strong>, que se obtiene gracias a un proceso especial de pintura con base ceramica. Esto da al producto un <strong>look m\u00e1s agresivo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Catalizador ACC.076.A1 incluido. Homologado E5+ (Reg.EC-UE 134\/2014). Tras la instalaci\u00f3n de este sistema de escape, es posible que se encienda la luz indicadora del motor (MIL). En tal caso, la instalaci\u00f3n opcional de la Switch-Off Key resolver\u00eda el inconveniente. Para m\u00e1s informaci\u00f3n, consulte la secci\u00f3n \u201cOptional Parts\u201d.<\/p>\n","protected":false},"featured_media":63736,"template":"","meta":{"_acf_changed":false},"product_brand":[21825,21566,21811],"product_cat":[685],"product_tag":[],"class_list":{"0":"post-104615","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2025-2026-10862","7":"product_brand-aprilia","8":"product_brand-tuono-125","9":"product_cat-escape-completo","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/104615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/63736"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=104615"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=104615"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=104615"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=104615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}