{"id":89236,"date":"2026-04-21T13:17:38","date_gmt":"2026-04-21T11:17:38","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/a-007-l7-aprilia-dorsoduro-750-2008-2020\/"},"modified":"2026-04-21T13:17:38","modified_gmt":"2026-04-21T11:17:38","slug":"a-007-l7-aprilia-dorsoduro-750-2008-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/a-007-l7-aprilia-dorsoduro-750-2008-2020\/","title":{"rendered":"A.007.L7 &#8211; APRILIA DORSODURO 750 2008 > 2020"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>La l\u00ednea SUONO es la s\u00edntesis perfecta entre <strong>est\u00e9tica, innovaci\u00f3n y tecnolog\u00eda<\/strong> aplicada. Para fabricarlo se han elegido los <strong>mejores materiales<\/strong> para garantizar al producto la <strong>m\u00e1xima ligereza.<\/strong><\/p>\n<p>Fabricado completamente en acero inox cepillado resistente a las altas temperaturas, este silenciador es el ideal para los amantes de las dos ruedas que no quieren renunciar al <strong>dise\u00f1o.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. La l\u00ednea SUONO es la s\u00edntesis perfecta entre est\u00e9tica, innovaci\u00f3n y tecnolog\u00eda aplicada. Para [&hellip;]<\/p>\n","protected":false},"featured_media":62590,"template":"","meta":{"_acf_changed":false},"product_brand":[21594,21566,21587],"product_cat":[846],"product_tag":[],"class_list":{"0":"post-89236","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2008-2016-dorsoduro-750","7":"product_brand-aprilia","8":"product_brand-dorsoduro-750","9":"product_cat-2-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/89236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/62590"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=89236"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=89236"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=89236"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=89236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}