{"id":89537,"date":"2026-04-21T13:19:31","date_gmt":"2026-04-21T11:19:31","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-010-lnc-bmw-k-1300-s-2009-2020\/"},"modified":"2026-04-21T13:19:31","modified_gmt":"2026-04-21T11:19:31","slug":"b-010-lnc-bmw-k-1300-s-2009-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/b-010-lnc-bmw-k-1300-s-2009-2020\/","title":{"rendered":"B.010.LNC \u2013 BMW K 1300 S 2009 > 2020"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>Los escapes de la l\u00ednea OVAL se adaptan perfectamente a todo tipo de motos. Acabado con gran atenci\u00f3n al detalle, es una l\u00ednea que representa el mejor compromiso entre el <strong>dise\u00f1o<\/strong> y el <strong>rendimiento<\/strong>. <\/p>\n<p>El escape se caracteriza por un cuerpo de <strong>titanio<\/strong> y una tapa de carbono de alta resistencia al calor. Adem\u00e1s tiene unas ranuras abiertas en la tapa, un detalle que da al escape un <strong>dise\u00f1o<\/strong> m\u00e1s <strong>deportivo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. Los escapes de la l\u00ednea OVAL se adaptan perfectamente a todo tipo de motos. [&hellip;]<\/p>\n","protected":false},"featured_media":62693,"template":"","meta":{"_acf_changed":false},"product_brand":[22343,22105,22336],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-89537","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2009-2016-k-1300-s","7":"product_brand-bmw","8":"product_brand-k-1300-s","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/89537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/62693"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=89537"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=89537"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=89537"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=89537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}