{"id":89838,"date":"2026-04-21T13:21:40","date_gmt":"2026-04-21T11:21:40","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-043-lxb-honda-cbr-125-r-2004-2010\/"},"modified":"2026-04-21T13:21:40","modified_gmt":"2026-04-21T11:21:40","slug":"h-043-lxb-honda-cbr-125-r-2004-2010","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/h-043-lxb-honda-cbr-125-r-2004-2010\/","title":{"rendered":"H.043.LXB &#8211; Honda CBR 125 R 2004 > 2010"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>Fabricado utilizando las soluciones t\u00e9cnicas de los escapes <strong>de competici\u00f3n<\/strong>, el escape GP es un silenciador redondo corto con boquillas agrandadas.<\/p>\n<p>El cuerpo central est\u00e1 fabricado en acero inox negro con efecto  <strong>\u201cBlack Moon\u201d<\/strong> obtenido por un proceso de coloraci\u00f3n especial. Esta versi\u00f3n da al producto un look m\u00e1s <strong>agresivo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. Fabricado utilizando las soluciones t\u00e9cnicas de los escapes de competici\u00f3n, el escape GP es [&hellip;]<\/p>\n","protected":false},"featured_media":62610,"template":"","meta":{"_acf_changed":false},"product_brand":[24142,24135,23848],"product_cat":[685],"product_tag":[],"class_list":{"0":"post-89838","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2004-2010-cbr-125-r","7":"product_brand-cbr-125-r","8":"product_brand-honda","9":"product_cat-escape-completo","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/89838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/62610"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=89838"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=89838"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=89838"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=89838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}