{"id":90139,"date":"2026-04-21T13:23:24","date_gmt":"2026-04-21T11:23:24","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/uh-037-l9-honda-cbr-600-rr-2013-2016\/"},"modified":"2026-04-21T13:23:24","modified_gmt":"2026-04-21T11:23:24","slug":"uh-037-l9-honda-cbr-600-rr-2013-2016","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/uh-037-l9-honda-cbr-600-rr-2013-2016\/","title":{"rendered":"UH.037.L9 &#8211; Honda CBR 600 RR 2013 > 2016"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>La l\u00ednea SUONO es la s\u00edntesis perfecta entre <strong>est\u00e9tica, innovaci\u00f3n y tecnolog\u00eda<\/strong> aplicada. Para fabricarlo se han elegido los <strong>mejores materiales<\/strong> para garantizar al producto la <strong>m\u00e1xima ligereza.<\/strong><\/p>\n<p>El silenciador est\u00e1 formado por un cuerpo central de acero inox de color negro <strong>\u201cBlack Moon\u201d<\/strong> obtenido por un proceso de coloraci\u00f3n especial. Esta versi\u00f3n da al producto un aspecto m\u00e1s <strong>agresivo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. La l\u00ednea SUONO es la s\u00edntesis perfecta entre est\u00e9tica, innovaci\u00f3n y tecnolog\u00eda aplicada. Para [&hellip;]<\/p>\n","protected":false},"featured_media":24967,"template":"","meta":{"_acf_changed":false},"product_brand":[24275,24247,23848],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-90139","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2013-2016-cbr-600-rr","7":"product_brand-cbr-600-rr","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/90139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/24967"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=90139"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=90139"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=90139"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=90139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}