{"id":90363,"date":"2026-04-21T13:25:00","date_gmt":"2026-04-21T11:25:00","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-036-lec-honda-xl-1000-varadero-2003-2011\/"},"modified":"2026-04-21T13:25:00","modified_gmt":"2026-04-21T11:25:00","slug":"h-036-lec-honda-xl-1000-varadero-2003-2011","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/h-036-lec-honda-xl-1000-varadero-2003-2011\/","title":{"rendered":"H.036.LEC &#8211; Honda XL 1000 VARADERO 2003 > 2011"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>Los escapes de la l\u00ednea OVAL se adaptan perfectamente a todo tipo de motos. Acabado con gran atenci\u00f3n al detalle, es una l\u00ednea que representa el mejor compromiso entre el <strong>dise\u00f1o<\/strong> y el <strong>rendimiento<\/strong>. <\/p>\n<p>Caracterizado por cuerpo y tapa de <strong>carbono<\/strong> de alta resistencia al calor, el escape tiene unas ranuras abiertas en la tapa, un detalle que da al escape un dise\u00f1o <strong>m\u00e1s deportivo<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. Los escapes de la l\u00ednea OVAL se adaptan perfectamente a todo tipo de motos. [&hellip;]<\/p>\n","protected":false},"featured_media":62642,"template":"","meta":{"_acf_changed":false},"product_brand":[24863,23848,24856],"product_cat":[846],"product_tag":[],"class_list":{"0":"post-90363","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2003-2011-xl-1000-varadero","7":"product_brand-honda","8":"product_brand-xl-1000-varadero","9":"product_cat-2-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/90363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/62642"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=90363"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=90363"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=90363"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=90363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}