{"id":94437,"date":"2026-04-21T13:52:20","date_gmt":"2026-04-21T11:52:20","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-059-c2-honda-crf-1000-l-africa-twin-2016-2019\/"},"modified":"2026-04-21T13:52:20","modified_gmt":"2026-04-21T11:52:20","slug":"h-059-c2-honda-crf-1000-l-africa-twin-2016-2019","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/h-059-c2-honda-crf-1000-l-africa-twin-2016-2019\/","title":{"rendered":"H.059.C2 &#8211; Honda CRF 1000 L AFRICA TWIN 2016 > 2019"},"content":{"rendered":"<p>Los tubos no kat opcionales de acero inox ofrecen una mejor\u00eda de las performance sobre todo cuando se acoplan con el silenciador slip-on Mivv. Este producto mejora tu moto garantizando un dise\u00f1o m\u00e1s bonito y un sound \u00fanico. Este producto no est\u00e1 homologado seg\u00fan las normativas vigentes para el uso de la moto en carretera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los tubos no kat opcionales de acero inox ofrecen una mejor\u00eda de las performance sobre todo cuando se acoplan con el silenciador slip-on Mivv. Este producto mejora tu moto garantizando un dise\u00f1o m\u00e1s bonito y un sound \u00fanico. Este producto no est\u00e1 homologado seg\u00fan las normativas vigentes para el uso de la moto en carretera.<\/p>\n","protected":false},"featured_media":25174,"template":"","meta":{"_acf_changed":false},"product_brand":[24359,24352,23848],"product_cat":[796],"product_tag":[],"class_list":{"0":"post-94437","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2016-2019-crf-1000-l-africa-twin","7":"product_brand-crf-1000-l-africa-twin","8":"product_brand-honda","9":"product_cat-tubo-no-kat","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/94437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/25174"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=94437"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=94437"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=94437"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=94437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}