{"id":95655,"date":"2026-04-21T14:01:01","date_gmt":"2026-04-21T12:01:01","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-033-sdrx-ducati-multistrada-1260-2018-2020\/"},"modified":"2026-04-21T14:01:01","modified_gmt":"2026-04-21T12:01:01","slug":"d-033-sdrx-ducati-multistrada-1260-2018-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/d-033-sdrx-ducati-multistrada-1260-2018-2020\/","title":{"rendered":"D.033.SDRX \u2013 DUCATI MULTISTRADA 1260 2018 > 2020"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>El escape DELTA RACE se caracteriza por una <strong> forma exclusiva<\/strong>  que, a trav\u00e9s de una transformaci\u00f3n gradual se hace de forma c\u00f3nica a <strong>hexagonal<\/strong> . Hay muchos detalles que hacen el estilo \u00fanico, como la tapa en carbono twill 3K; la abrazadera perimetral con <strong>doble remachado<\/strong> ; el casquillo de entrada fabricado solidamente, para ofrecer la maxima precisi\u00f3n de enganche. En el terminal est\u00e1 el caracteristico logo Mivv realizado por la tecnolog\u00eda Laser.<\/p>\n<p>Se caracteriza por un cuerpo de acero inox peinado con effecto <strong>\u201cpearled\u201d<\/strong>, que se obtiene por medio de un proceso especial de manufactura. Esto da al producto un <strong>look inimitable<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La instalaci\u00f3n de este escape requiere la reasignaci\u00f3n de la ECU. Para obtener m\u00e1s informaci\u00f3n, lea la informaci\u00f3n t\u00e9cnica en el cuadro de documentaci\u00f3n.<\/p>\n","protected":false},"featured_media":63843,"template":"","meta":{"_acf_changed":false},"product_brand":[23309,22770,23302],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-95655","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2018-multistrada-1260","7":"product_brand-ducati","8":"product_brand-multistrada-1260","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/95655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/63843"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=95655"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=95655"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=95655"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=95655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}