{"id":96040,"date":"2026-04-21T14:03:53","date_gmt":"2026-04-21T12:03:53","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-042-sm3c-ducati-monster-1200-2017-2021\/"},"modified":"2026-04-21T14:03:53","modified_gmt":"2026-04-21T12:03:53","slug":"d-042-sm3c-ducati-monster-1200-2017-2021","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/d-042-sm3c-ducati-monster-1200-2017-2021\/","title":{"rendered":"D.042.SM3C \u2013 DUCATI MONSTER 1200 2017 > 2021"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>La l\u00ednea <strong>MK3<\/strong>, que es el resultado de la experiencia ganada en los campeonatos mundiales <strong>Moto3 y Moto2<\/strong> , es la s\u00edntesi perfecta entre la <strong>prestaci\u00f3n y la tecnolog\u00eda<\/strong>. Con un <strong>dise\u00f1o<\/strong> parecido con los escapes fabricados para el <strong>Campeonato del Mundo Moto3<\/strong> MK3, es un producto con dimensiones <strong>compactas<\/strong> , que puede desarrollar el agradable <strong>sonido MIVV<\/strong>. <\/p>\n<p>La versi\u00f3n\u00a0carbono\u00a0se caracteriza por un cuerpo central de <strong>carbono brillante<\/strong> que junto con la reja de protecci\u00f3n en el fondillo de salida, da al producto un <strong>look high tech<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. La l\u00ednea MK3, que es el resultado de la experiencia ganada en los campeonatos [&hellip;]<\/p>\n","protected":false},"featured_media":64265,"template":"","meta":{"_acf_changed":false},"product_brand":[23036,22770,23029],"product_cat":[846],"product_tag":[],"class_list":{"0":"post-96040","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2017-monster-1200","7":"product_brand-ducati","8":"product_brand-monster-1200","9":"product_cat-2-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/96040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/64265"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=96040"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=96040"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=96040"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=96040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}