{"id":96208,"date":"2026-04-21T14:05:05","date_gmt":"2026-04-21T12:05:05","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-041-l2p-ducati-monster-1200-2017-2021\/"},"modified":"2026-04-21T14:05:05","modified_gmt":"2026-04-21T12:05:05","slug":"d-041-l2p-ducati-monster-1200-2017-2021","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/d-041-l2p-ducati-monster-1200-2017-2021\/","title":{"rendered":"D.041.L2P \u2013 DUCATI MONSTER 1200 2017 > 2021"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>GP PRO tiene una <strong>soldadura a TIG semiartesanal<\/strong>, un <strong>dise\u00f1o compacto<\/strong> y esencial y un <strong>sonido agresivo<\/strong>. El tubo de salida gracias a la inspiraci\u00f3n del mundo de las <strong>competiciones<\/strong> est\u00e1 equipado con una <strong>reja de protecci\u00f3n removible<\/strong> que esconde el dB-killer. En el terminal est\u00e1 el caracteristico logo Mivv realizado por la tecnolog\u00eda Laser.<\/p>\n<p>Se caracteriza por un cuerpo central de <strong>carbono con manufactura brillante<\/strong>. Esto es el producto <strong>ideal para los que exigen lo mejor en look y tecnolog\u00eda.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. GP PRO tiene una soldadura a TIG semiartesanal, un dise\u00f1o compacto y esencial y [&hellip;]<\/p>\n","protected":false},"featured_media":63702,"template":"","meta":{"_acf_changed":false},"product_brand":[23036,22770,23029],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-96208","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2017-monster-1200","7":"product_brand-ducati","8":"product_brand-monster-1200","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/96208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/63702"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=96208"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=96208"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=96208"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=96208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}