{"id":96684,"date":"2026-04-21T14:08:52","date_gmt":"2026-04-21T12:08:52","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-072-lxbp-honda-cbr-650-r-2019-2023\/"},"modified":"2026-04-21T14:08:52","modified_gmt":"2026-04-21T12:08:52","slug":"h-072-lxbp-honda-cbr-650-r-2019-2023","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/h-072-lxbp-honda-cbr-650-r-2019-2023\/","title":{"rendered":"H.072.LXBP- HONDA CBR 650 R 2019 > 2023"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>GP PRO tiene una <strong>soldadura a TIG semiartesanal<\/strong>, un <strong>dise\u00f1o compacto<\/strong> y esencial y un <strong>sonido agresivo<\/strong>. El tubo de salida gracias a la inspiraci\u00f3n del mundo de las <strong>competiciones<\/strong> est\u00e1 equipado con una <strong>reja de protecci\u00f3n removible<\/strong> que esconde el dB-killer. En el terminal est\u00e1 el caracteristico logo Mivv realizado por la tecnolog\u00eda Laser.<\/p>\n<p>Se caracteriza por un cuerpo central de acero inox negro con efecto cepillado <strong>\u201cBlack Moon\u201d<\/strong>, obtenido por un proceso de coloraci\u00f3n especial. Esta versi\u00f3n da al producto un <strong>aspecto m\u00e1s agresivo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. GP PRO tiene una soldadura a TIG semiartesanal, un dise\u00f1o compacto y esencial y [&hellip;]<\/p>\n","protected":false},"featured_media":25370,"template":"","meta":{"_acf_changed":false},"product_brand":[24296,24289,23848],"product_cat":[685],"product_tag":[],"class_list":{"0":"post-96684","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2019-cbr-650-r","7":"product_brand-cbr-650-r","8":"product_brand-honda","9":"product_cat-escape-completo","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/96684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/25370"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=96684"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=96684"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=96684"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=96684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}