{"id":97720,"date":"2026-04-21T14:17:27","date_gmt":"2026-04-21T12:17:27","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-038-lc4b-bmw-f-900-r-2020-2024\/"},"modified":"2026-04-21T14:17:27","modified_gmt":"2026-04-21T12:17:27","slug":"b-038-lc4b-bmw-f-900-r-2020-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/b-038-lc4b-bmw-f-900-r-2020-2024\/","title":{"rendered":"B.038.LC4B \u2013 BMW F 900 R 2020 > 2024"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>La l\u00ednea <strong>X-M1<\/strong>,  es el resultado de la experiencia conseguida en los campeonatos mundiales <strong>MotoGP y Moto2<\/strong>, es la s\u00edntesi perfecta entre las <strong>prestaciones<\/strong> y el <strong>estilo racing<\/strong>. Con un <strong>dise\u00f1o<\/strong> parecido a los escapes fabricados para el Campeonato del Mundo de Motociclismo , el escape <strong>X-M1<\/strong> ofrece una forma <strong>c\u00f3nica<\/strong> y  dimensiones <strong>compactas<\/strong> capaces de desarrollar el agradable <strong>sonido<\/strong> MIVV. <\/p>\n<p>La versi\u00f3n <strong>black<\/strong> se caracteriza por un cuerpo central de acero inox negro 304 con efecto <strong>\u201cBlack Moon\u201d<\/strong> obtenido por medio de un proceso especial de pintura con ceramica.<\/p>\n<p><strong>X-M1 puro estilo italiano.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HOMOLOGADO EURO 5. Compatible solo con las bolsas laterales originales<\/p>\n","protected":false},"featured_media":7834,"template":"","meta":{"_acf_changed":false},"product_brand":[22245,22105,22238],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-97720","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2020-f-900-r","7":"product_brand-bmw","8":"product_brand-f-900-r","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/97720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/7834"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=97720"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=97720"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=97720"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=97720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}