{"id":97860,"date":"2026-04-21T14:18:50","date_gmt":"2026-04-21T12:18:50","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-030-lm3c-bmw-s-1000-r-2017-2020\/"},"modified":"2026-04-21T14:18:50","modified_gmt":"2026-04-21T12:18:50","slug":"b-030-lm3c-bmw-s-1000-r-2017-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/b-030-lm3c-bmw-s-1000-r-2017-2020\/","title":{"rendered":"B.030.LM3C \u2013 BMW S 1000 R 2017 > 2020"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>La l\u00ednea <strong>MK3<\/strong>, que es el resultado de la experiencia ganada en los campeonatos mundiales <strong>Moto3 y Moto2<\/strong> , es la s\u00edntesi perfecta entre la <strong>prestaci\u00f3n y la tecnolog\u00eda<\/strong>. Con un <strong>dise\u00f1o<\/strong> parecido con los escapes fabricados para el <strong>Campeonato del Mundo Moto3<\/strong> MK3, es un producto con dimensiones <strong>compactas<\/strong> , que puede desarrollar el agradable <strong>sonido MIVV<\/strong>. <\/p>\n<p>La versi\u00f3n\u00a0carbono\u00a0se caracteriza por un cuerpo central de <strong>carbono brillante<\/strong> que junto con la reja de protecci\u00f3n en el fondillo de salida, da al producto un <strong>look high tech<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. La l\u00ednea MK3, que es el resultado de la experiencia ganada en los campeonatos [&hellip;]<\/p>\n","protected":false},"featured_media":64181,"template":"","meta":{"_acf_changed":false},"product_brand":[22504,22105,22497],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-97860","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2017-s-1000-r","7":"product_brand-bmw","8":"product_brand-s-1000-r","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/97860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/64181"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=97860"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=97860"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=97860"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=97860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}