{"id":98588,"date":"2026-04-21T14:24:42","date_gmt":"2026-04-21T12:24:42","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/d-048-lc5b-ducati-monster-937-monster-937-2021-2024\/"},"modified":"2026-04-21T14:24:42","modified_gmt":"2026-04-21T12:24:42","slug":"d-048-lc5b-ducati-monster-937-monster-937-2021-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/es\/product\/d-048-lc5b-ducati-monster-937-monster-937-2021-2024\/","title":{"rendered":"D.048.LC5B \u2013 DUCATI MONSTER 937 \/ MONSTER 937 + 2021 > 2024"},"content":{"rendered":"<p>Hecho para mejorar <strong>est\u00e9tica, sound y rendimiento<\/strong> de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren <strong>distinguirse<\/strong>, tambi\u00e9n por el look de su propia moto.<\/p>\n<p>La l\u00ednea Mivv <strong>X-M5<\/strong>, es el resultado de la experiencia conseguida en los campeonatos mundiales <strong>MotoGP , Moto2 y Moto3<\/strong>, es la s\u00edntesi perfecta entre las <strong>prestaciones<\/strong> y el <strong>estilo racing<\/strong>. Con un <strong>dise\u00f1o<\/strong> parecido a los escapes fabricados para el Campeonato del Mundo de Motociclismo , el escape <strong>X-M5<\/strong> ofrece una forma <strong>c\u00f3nica<\/strong> y dimensiones <strong>compactas<\/strong> capaces de desarrollar el agradable <strong>sonido<\/strong> MIVV. <\/p>\n<p>El escape tiene una tapa de <strong>carbono<\/strong> twill 3K y est\u00e1 equipado con <strong>una rejilla de protecci\u00f3n removible<\/strong>, que esconde el dB-killer<\/p>\n<p>La versi\u00f3n <strong>black<\/strong> se caracteriza por un cuerpo central de acero inox negro 304 con efecto <strong>\u201cBlack Moon\u201d<\/strong> obtenido por medio de un proceso especial de pintura con ceramica.<\/p>\n<p><strong>X-M5 puro estilo italiano<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hecho para mejorar est\u00e9tica, sound y rendimiento de la moto, el escape slip-on Mivv nace a partir de la m\u00e1xima atenci\u00f3n al dise\u00f1o, con el objetivo de satisfacer a los que quieren distinguirse, tambi\u00e9n por el look de su propia moto. La l\u00ednea Mivv X-M5, es el resultado de la experiencia conseguida en los campeonatos [&hellip;]<\/p>\n","protected":false},"featured_media":64959,"template":"","meta":{"_acf_changed":false},"product_brand":[23197,22770,23190],"product_cat":[702],"product_tag":[],"class_list":{"0":"post-98588","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2021-monster","7":"product_brand-ducati","8":"product_brand-monster-937","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product\/98588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media\/64959"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/media?parent=98588"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_brand?post=98588"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_cat?post=98588"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/es\/wp-json\/wp\/v2\/product_tag?post=98588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}