{"id":100294,"date":"2026-04-21T14:39:14","date_gmt":"2026-04-21T12:39:14","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/acc-070-0-honda-cb-750-hornet-2023-2024\/"},"modified":"2026-04-21T14:39:14","modified_gmt":"2026-04-21T12:39:14","slug":"acc-070-0-honda-cb-750-hornet-2023-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/fr\/product\/acc-070-0-honda-cb-750-hornet-2023-2024\/","title":{"rendered":"ACC.070.0 \u2013 HONDA CB 750 HORNET 2023> 2024"},"content":{"rendered":"<p>Ce pare-chaleur en <strong>fibre de carbone<\/strong> a \u00e9t\u00e9 con\u00e7u sp\u00e9cifiquement pour le syst\u00e8me d&rsquo;\u00e9chappement de cette moto. Ce produit <strong>optionnel<\/strong> facile \u00e0 installer donne un aspect <strong>plus sportif<\/strong> \u00e0 l&rsquo;ensemble du syst\u00e8me d&rsquo;\u00e9chappement et <strong>\u00e9vite le contact<\/strong> direct avec les parties du syst\u00e8me o\u00f9 des <strong>pics de chaleur<\/strong> \u00e9lev\u00e9s sont atteints.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce pare-chaleur en fibre de carbone a \u00e9t\u00e9 con\u00e7u sp\u00e9cifiquement pour le syst\u00e8me d&rsquo;\u00e9chappement de cette moto. Ce produit optionnel facile \u00e0 installer donne un aspect plus sportif \u00e0 l&rsquo;ensemble du syst\u00e8me d&rsquo;\u00e9chappement et \u00e9vite le contact direct avec les parties du syst\u00e8me o\u00f9 des pics de chaleur \u00e9lev\u00e9s sont atteints.<\/p>\n","protected":false},"featured_media":5782,"template":"","meta":{"_acf_changed":false},"product_brand":[24056,24049,23846],"product_cat":[758],"product_tag":[],"class_list":{"0":"post-100294","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2023-cb-750-hornet","7":"product_brand-cb-750-hornet","8":"product_brand-honda","9":"product_cat-carter-pare-chaleur","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product\/100294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media\/5782"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media?parent=100294"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_brand?post=100294"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_cat?post=100294"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_tag?post=100294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}