{"id":101953,"date":"2026-04-21T14:54:12","date_gmt":"2026-04-21T12:54:12","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-043-ldkx-bmw-f-900-gs-2024-2026\/"},"modified":"2026-04-21T14:54:12","modified_gmt":"2026-04-21T12:54:12","slug":"b-043-ldkx-bmw-f-900-gs-2024-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/fr\/product\/b-043-ldkx-bmw-f-900-gs-2024-2026\/","title":{"rendered":"B.043.LDKX &#8211; BMW F 900 GS 2024 > 2026"},"content":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer <strong>l\u2019aspect, le son et les prestations<\/strong> de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se <strong>d\u00e9marquer<\/strong> aussi par l\u2019allure de leur moto.<\/p>\n<p>Le projet \u00e9chappement \u2018Dakar\u2019 est le r\u00e9sultat de l&rsquo;exp\u00e9rience de notre R&#038;D dans les <strong>courses rallye.<\/strong><\/p>\n<p>Le r\u00e9sultat est un <strong>pot d\u2019\u00e9chappement essentiel et robuste<\/strong>, id\u00e9ale pour tous ceux qui pr\u00e9f\u00e8rent faire un tout-terrain plus <strong>exigeant<\/strong>.<\/p>\n<p>Le pot est en <strong>acier inox 304<\/strong> avec l&rsquo;ajout d&rsquo;une finition sp\u00e9ciale <strong>\u2018pearled\u2019<\/strong> qui le rend <strong>\u2018highly resistant\u2019.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer l\u2019aspect, le son et les prestations de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se d\u00e9marquer aussi par l\u2019allure de leur moto. Le projet \u00e9chappement \u2018Dakar\u2019 est le r\u00e9sultat de l&rsquo;exp\u00e9rience de notre R&#038;D dans les courses rallye. [&hellip;]<\/p>\n","protected":false},"featured_media":62533,"template":"","meta":{"_acf_changed":false},"product_brand":[22229,22103,22222],"product_cat":[704],"product_tag":[],"class_list":{"0":"post-101953","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2024-2026-11237","7":"product_brand-bmw","8":"product_brand-f-900-gs","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product\/101953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media\/62533"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media?parent=101953"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_brand?post=101953"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_cat?post=101953"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_tag?post=101953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}