{"id":104438,"date":"2026-04-21T15:16:40","date_gmt":"2026-04-21T13:16:40","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/acc-101-0-honda-cbr-500-r-2024-2026\/"},"modified":"2026-04-21T15:16:40","modified_gmt":"2026-04-21T13:16:40","slug":"acc-101-0-honda-cbr-500-r-2024-2026","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/fr\/product\/acc-101-0-honda-cbr-500-r-2024-2026\/","title":{"rendered":"ACC.101.0 &#8211; HONDA CBR 500 R 2024 > 2026"},"content":{"rendered":"<p><p>MIVV SWITCH OFF KEY est un dispositif &eacute;lectronique plug and play d&rsquo;autodiagnostic (OBD) pour motos Euro5+ dot&eacute; des fonctions suivantes:<\/p>\n<ul>\n<li>Il &eacute;teint le voyant de panne moteur (Check Engine) en cas d&rsquo;allumage d&ucirc; au remplacement du catalyseur d&rsquo;origine par un mod&egrave;le de rechange, susceptible d&rsquo;alt&eacute;rer les param&egrave;tres d&rsquo;oxyg&egrave;ne par rapport &agrave; ceux pr&eacute;d&eacute;finis par le r&eacute;glage du bo&icirc;tier &eacute;lectronique d&rsquo;origine.<\/li>\n<li>L&rsquo;extinction du voyant Check Engine pr&eacute;serve en m&ecirc;me temps le bon fonctionnement du diagnostic embarqu&eacute;.<\/li>\n<li>Il n&rsquo;intervient en aucune mani&egrave;re sur la programmation d&rsquo;origine du bo&icirc;tier &eacute;lectronique du moteur ni sur d&rsquo;autres param&egrave;tres &eacute;lectroniques du v&eacute;hicule.<\/li>\n<\/ul>\n<p>Produit non approuv&eacute;.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MIVV SWITCH OFF KEY est un dispositif &eacute;lectronique plug and play d&rsquo;autodiagnostic (OBD) pour motos Euro5+ dot&eacute; des fonctions suivantes: Il &eacute;teint le voyant de panne moteur (Check Engine) en cas d&rsquo;allumage d&ucirc; au remplacement du catalyseur d&rsquo;origine par un mod&egrave;le de rechange, susceptible d&rsquo;alt&eacute;rer les param&egrave;tres d&rsquo;oxyg&egrave;ne par rapport &agrave; ceux pr&eacute;d&eacute;finis par le [&hellip;]<\/p>\n","protected":false},"featured_media":5898,"template":"","meta":{"_acf_changed":false},"product_brand":[24189,24168,23846],"product_cat":[840],"product_tag":[],"class_list":{"0":"post-104438","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2024-2026-625","7":"product_brand-cbr-500-r","8":"product_brand-honda","9":"product_cat-cle-de-desactivation","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product\/104438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media\/5898"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media?parent=104438"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_brand?post=104438"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_cat?post=104438"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_tag?post=104438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}