{"id":89389,"date":"2026-04-21T13:18:36","date_gmt":"2026-04-21T11:18:36","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-008-lec-bmw-f-800-r-2009-2020\/"},"modified":"2026-04-21T13:18:36","modified_gmt":"2026-04-21T11:18:36","slug":"b-008-lec-bmw-f-800-r-2009-2020","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/fr\/product\/b-008-lec-bmw-f-800-r-2009-2020\/","title":{"rendered":"B.008.LEC &#8211; BMW F 800 R 2009 > 2020"},"content":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer <strong>l\u2019aspect, le son et les prestations<\/strong> de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se <strong>d\u00e9marquer<\/strong> aussi par l\u2019allure de leur moto.<\/p>\n<p>L\u2019\u00e9chappement OVAL s\u2019adapte parfaitement \u00e0 n\u2019importe quel type de moto. Peaufin\u00e9 dans les moindres d\u00e9tails, c\u2019est une ligne qui repr\u00e9sente le meilleur compromis entre <strong>design<\/strong> et <strong>performances.<\/strong><\/p>\n<p>Caract\u00e9ris\u00e9 par un corps et un embout en <strong>carbone<\/strong> \u00e0 haute r\u00e9sistance thermique, l\u2019\u00e9chappement pr\u00e9sente des fentes ouvertes sur l\u2019embout qui donnent au silencieux un design plus <strong>sportif.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer l\u2019aspect, le son et les prestations de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se d\u00e9marquer aussi par l\u2019allure de leur moto. L\u2019\u00e9chappement OVAL s\u2019adapte parfaitement \u00e0 n\u2019importe quel type de moto. Peaufin\u00e9 dans les moindres d\u00e9tails, c\u2019est [&hellip;]<\/p>\n","protected":false},"featured_media":62642,"template":"","meta":{"_acf_changed":false},"product_brand":[22188,22103,22181],"product_cat":[704],"product_tag":[],"class_list":{"0":"post-89389","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2009-f-800-r","7":"product_brand-bmw","8":"product_brand-f-800-r-gt","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product\/89389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media\/62642"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media?parent=89389"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_brand?post=89389"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_cat?post=89389"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_tag?post=89389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}