{"id":90067,"date":"2026-04-21T13:22:58","date_gmt":"2026-04-21T11:22:58","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/h-038-l9-honda-cbr-600-f-2011-2013\/"},"modified":"2026-04-21T13:22:58","modified_gmt":"2026-04-21T11:22:58","slug":"h-038-l9-honda-cbr-600-f-2011-2013","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/fr\/product\/h-038-l9-honda-cbr-600-f-2011-2013\/","title":{"rendered":"H.038.L9 &#8211; Honda CBR 600 F 2011 > 2013"},"content":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer <strong>l\u2019aspect, le son et les prestations<\/strong> de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se <strong>d\u00e9marquer<\/strong> aussi par l\u2019allure de leur moto.<\/p>\n<p>La ligne SUONO est la synth\u00e8se parfaite entre <strong>esth\u00e9tique, innovation et technologie<\/strong> appliqu\u00e9e. Lorsque nous l\u2019avons con\u00e7ue, nous avons choisi les <strong>meilleurs mat\u00e9riaux<\/strong> pour garantir au produit la <strong>l\u00e9g\u00e8ret\u00e9 maximale.<\/strong><\/p>\n<p>La version noir est form\u00e9e d\u2019un corps central en acier inox noir <strong>\u201cBlack Moon\u201d<\/strong>, obtenu avec un processus sp\u00e9cial de coloration qui rend le pot plus <strong>agressif.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer l\u2019aspect, le son et les prestations de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se d\u00e9marquer aussi par l\u2019allure de leur moto. La ligne SUONO est la synth\u00e8se parfaite entre esth\u00e9tique, innovation et technologie appliqu\u00e9e. Lorsque nous l\u2019avons [&hellip;]<\/p>\n","protected":false},"featured_media":62600,"template":"","meta":{"_acf_changed":false},"product_brand":[24224,24196,23846],"product_cat":[704],"product_tag":[],"class_list":{"0":"post-90067","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2011-2013-cbr-600-f","7":"product_brand-cbr-600-f","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product\/90067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media\/62600"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media?parent=90067"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_brand?post=90067"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_cat?post=90067"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_tag?post=90067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}