{"id":93763,"date":"2026-04-21T13:47:57","date_gmt":"2026-04-21T11:47:57","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/uh-032-lx2-honda-cbr-1000-rr-2006-2007\/"},"modified":"2026-04-21T13:47:57","modified_gmt":"2026-04-21T11:47:57","slug":"uh-032-lx2-honda-cbr-1000-rr-2006-2007","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/fr\/product\/uh-032-lx2-honda-cbr-1000-rr-2006-2007\/","title":{"rendered":"UH.032.LX2 &#8211; HONDA CBR 1000 RR 2006 > 2007"},"content":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer <strong>l\u2019aspect, le son et les prestations<\/strong> de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se <strong>d\u00e9marquer<\/strong> aussi par l\u2019allure de leur moto.<\/p>\n<p>L\u2019\u00e9chappement OVAL s\u2019adapte parfaitement \u00e0 n\u2019importe quel type de moto. Peaufin\u00e9 dans les moindres d\u00e9tails, c\u2019est une ligne qui repr\u00e9sente le meilleur compromis entre <strong>design<\/strong> et <strong>performances.<\/strong><\/p>\n<p>Le corps en acier inox <strong>bross\u00e9<\/strong> conf\u00e8re \u00e0 ce silencieux la <strong>finition naturelle<\/strong> du m\u00e9tal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer l\u2019aspect, le son et les prestations de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se d\u00e9marquer aussi par l\u2019allure de leur moto. L\u2019\u00e9chappement OVAL s\u2019adapte parfaitement \u00e0 n\u2019importe quel type de moto. Peaufin\u00e9 dans les moindres d\u00e9tails, c\u2019est [&hellip;]<\/p>\n","protected":false},"featured_media":25108,"template":"","meta":{"_acf_changed":false},"product_brand":[24098,24084,23846],"product_cat":[704],"product_tag":[],"class_list":{"0":"post-93763","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2006-2007-cbr-1000-rr","7":"product_brand-cbr-1000-rr","8":"product_brand-honda","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product\/93763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media\/25108"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media?parent=93763"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_brand?post=93763"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_cat?post=93763"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_tag?post=93763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}