{"id":95590,"date":"2026-04-21T14:00:31","date_gmt":"2026-04-21T12:00:31","guid":{"rendered":"https:\/\/dev.mivv.com\/scarico-moto\/b-033-ldrx-bmw-f-850-gs-2018-2024\/"},"modified":"2026-04-21T14:00:31","modified_gmt":"2026-04-21T12:00:31","slug":"b-033-ldrx-bmw-f-850-gs-2018-2024","status":"publish","type":"product","link":"https:\/\/dev.mivv.com\/fr\/product\/b-033-ldrx-bmw-f-850-gs-2018-2024\/","title":{"rendered":"B.033.LDRX \u2013 BMW F 850 GS 2018 > 2024"},"content":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer <strong>l\u2019aspect, le son et les prestations<\/strong> de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se <strong>d\u00e9marquer<\/strong> aussi par l\u2019allure de leur moto.<\/p>\n<p>Le pot DELTA RACE a une <strong>forme incomparable<\/strong>, m\u00e9tamorphose graduelle de conique \u00e0 <strong>hexagonale<\/strong>. Plusieurs d\u00e9tailles rendent son style unique, comme l\u2019embout en carbone twill 3K\u00a0; le collier \u00e0 <strong>double file de rivets<\/strong>; l\u2019entr\u00e9e usin\u00e9e qui garantit un couplage de haute pr\u00e9cision. Le logo Mivv sur son corps est enfin marqu\u00e9 par laser.<\/p>\n<p>Le corps en acier bross\u00e9 \u00e0 l\u2019aspect <strong>\u201cperl\u00e9\u201d<\/strong>, obtenu par un traitement sp\u00e9cial lui donnant une <strong>allure inimitable<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9alis\u00e9 pour am\u00e9liorer l\u2019aspect, le son et les prestations de la moto, le pot slip-on Mivv est issu de l\u2019attention maximale vers le design, en vue de satisfaire ceux qui souhaitent se d\u00e9marquer aussi par l\u2019allure de leur moto. Le pot DELTA RACE a une forme incomparable, m\u00e9tamorphose graduelle de conique \u00e0 hexagonale. Plusieurs d\u00e9tailles [&hellip;]<\/p>\n","protected":false},"featured_media":63843,"template":"","meta":{"_acf_changed":false},"product_brand":[22215,22103,22208],"product_cat":[704],"product_tag":[],"class_list":{"0":"post-95590","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-2018-f-850-gs","7":"product_brand-bmw","8":"product_brand-f-850-gs","9":"product_cat-slip-on","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product\/95590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media\/63843"}],"wp:attachment":[{"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/media?parent=95590"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_brand?post=95590"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_cat?post=95590"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.mivv.com\/fr\/wp-json\/wp\/v2\/product_tag?post=95590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}